{"id":170360,"date":"2026-02-02T17:38:04","date_gmt":"2026-02-02T22:38:04","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=170360"},"modified":"2026-02-02T17:38:04","modified_gmt":"2026-02-02T22:38:04","slug":"aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/","title":{"rendered":"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC"},"content":{"rendered":"<a href=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/02\/AVISO-DE-SUSPENSAO-CONCORRENCIA-007.25.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"on\">AVISO DE SUSPENS\u00c3O - CONCORR\u00caNCIA 007.25<\/a>\n","protected":false},"excerpt":{"rendered":"AVISO DE SUSPENS\u00c3O - CONCORR\u00caNCIA 007.25","protected":false},"author":4,"featured_media":167458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","jnews_video_option_group":[[]],"override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"footnotes":""},"categories":[239,200],"tags":[],"class_list":["post-170360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capa","category-editais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC - Agazeta.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T22:38:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Agazeta.Net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agazeta.Net\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/\",\"name\":\"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp\",\"datePublished\":\"2026-02-02T22:38:04+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp\",\"width\":750,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535\",\"name\":\"Agazeta.Net\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/agazeta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/","og_locale":"pt_BR","og_type":"article","og_title":"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC - Agazeta.net","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/","og_site_name":"Agazeta.net","article_published_time":"2026-02-02T22:38:04+00:00","og_image":[{"width":750,"height":375,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp","type":"image\/webp"}],"author":"Agazeta.Net","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agazeta.Net","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/","name":"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp","datePublished":"2026-02-02T22:38:04+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/12\/senac-1-jpg-1-2.webp","width":750,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/aviso-de-suspensao-concorrencia-no-007-2025-senac-dr-ac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"Aviso de Suspens\u00e3o Concorr\u00eancia N\u00ba 007\/2025 Senac-DR\/AC"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535","name":"Agazeta.Net","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/agazeta\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/170360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=170360"}],"version-history":[{"count":1,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/170360\/revisions"}],"predecessor-version":[{"id":170363,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/170360\/revisions\/170363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/167458"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=170360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=170360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=170360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}