{"id":170190,"date":"2026-01-30T08:01:23","date_gmt":"2026-01-30T13:01:23","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=170190"},"modified":"2026-01-30T08:01:23","modified_gmt":"2026-01-30T13:01:23","slug":"rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/","title":{"rendered":"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Pela segunda vez em 2026, o Rio Acre ultrapassou a cota de transbordo em Rio Branco.<\/strong> De acordo com o Boletim da Defesa Civil Municipal, divulgado na manh\u00e3 desta sexta-feira (30), o n\u00edvel do manancial atingiu 14,39 metros \u00e0s 05h17, superando o limite de transbordo, que \u00e9 de 14,00 metros.<\/p>\n<p style=\"text-align: justify;\">Nas \u00faltimas 24 horas, a capital registrou 01,00 mil\u00edmetro de chuva, volume considerado baixo em compara\u00e7\u00e3o ao dia anterior, mas insuficiente para conter a eleva\u00e7\u00e3o cont\u00ednua do rio, que j\u00e1 vinha apresentando tend\u00eancia de subida desde a madrugada de quinta-feira (29).<\/p>\n<p style=\"text-align: justify;\">O comparativo do n\u00edvel do Rio Acre ao longo da quinta-feira (29) mostra uma eleva\u00e7\u00e3o gradual e constante,<strong> com avan\u00e7o m\u00e9dio a cada intervalo de quatro horas.<\/strong> \u00c0s 05h22, o rio estava em 13,50 metros, atingindo a cota de alerta. <strong>Quatro horas depois, \u00e0s 09h, subiu para 13,64 metros, um aumento de 14 cent\u00edmetros.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ao meio-dia, o n\u00edvel chegou a 13,77 metros, registrando mais 13 cent\u00edmetros de eleva\u00e7\u00e3o. No in\u00edcio da tarde, \u00e0s 15h, marcou 13,89 metros, mantendo o ritmo de subida.<strong> J\u00e1 \u00e0s 18h, o rio atingiu 14,00 metros, momento em que a cota de transbordo foi oficialmente alcan\u00e7ada.<\/strong><\/p>\n<p style=\"text-align: justify;\">A eleva\u00e7\u00e3o continuou durante a noite. \u00c0s 21h, o n\u00edvel chegou a 14,14 metros, e \u00e0 meia-noite marcou 14,20 metros, <strong>totalizando uma eleva\u00e7\u00e3o de 70 cent\u00edmetros em menos de 19 horas.<\/strong> No per\u00edodo, o volume de chuva registrado foi de 15,00 mil\u00edmetros.<\/p>\n<p style=\"text-align: justify;\">Equipes permanecem de prontid\u00e3o para eventuais a\u00e7\u00f5es de resposta, caso o n\u00edvel continue subindo nas pr\u00f3ximas horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pela segunda vez em 2026, o Rio Acre ultrapassou a cota de transbordo em Rio Branco. De acordo com o Boletim da Defesa Civil Municipal, divulgado na manh\u00e3 desta sexta-feira (30), o n\u00edvel do manancial atingiu 14,39 metros \u00e0s 05h17, superando o limite de transbordo, que \u00e9 de 14,00 metros. Nas \u00faltimas 24 horas, a [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":170191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","jnews_video_option_group":[[]],"override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"O n\u00edvel do manancial atingiu 14,39 metros \u00e0s 05h17, superando o limite de transbordo, que \u00e9 de 14,00 metros"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"footnotes":""},"categories":[54],"tags":[152],"class_list":["post-170190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco\" \/>\n<meta property=\"og:description\" content=\"O n\u00edvel do manancial atingiu 14,39 metros \u00e0s 05h17, superando o limite de transbordo, que \u00e9 de 14,00 metros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T13:01:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danniely Avlis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danniely Avlis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/\",\"name\":\"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg\",\"datePublished\":\"2026-01-30T13:01:23+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg\",\"width\":800,\"height\":405,\"caption\":\"Foto: Danniely Avlis \/ Agazeta.net\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579\",\"name\":\"Danniely Avlis\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/danniely\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/","og_locale":"pt_BR","og_type":"article","og_title":"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco","og_description":"O n\u00edvel do manancial atingiu 14,39 metros \u00e0s 05h17, superando o limite de transbordo, que \u00e9 de 14,00 metros","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/","og_site_name":"Agazeta.net","article_published_time":"2026-01-30T13:01:23+00:00","og_image":[{"width":800,"height":405,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg","type":"image\/jpeg"}],"author":"Danniely Avlis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Danniely Avlis","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/","name":"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg","datePublished":"2026-01-30T13:01:23+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-29-at-2.09.01-PM.jpeg","width":800,"height":405,"caption":"Foto: Danniely Avlis \/ Agazeta.net"},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/rio-acre-ultrapassa-cota-de-transbordo-pela-segunda-vez-no-ano-em-rio-branco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"Rio Acre ultrapassa cota de transbordo pela segunda vez no ano em Rio Branco"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579","name":"Danniely Avlis","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/danniely\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/170190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=170190"}],"version-history":[{"count":1,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/170190\/revisions"}],"predecessor-version":[{"id":170193,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/170190\/revisions\/170193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/170191"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=170190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=170190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=170190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}