{"id":169687,"date":"2026-01-21T11:51:34","date_gmt":"2026-01-21T16:51:34","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=169687"},"modified":"2026-01-21T11:51:34","modified_gmt":"2026-01-21T16:51:34","slug":"acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/","title":{"rendered":"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro"},"content":{"rendered":"<p style=\"text-align: justify;\">O deputado federal Coronel Ulysses anunciou nesta quarta-feira (21), por meio de um v\u00eddeo publicado em suas redes sociais, que ir\u00e1 se juntar \u00e0 chamada \u201ccaminhada pela liberdade\u201d, <strong>mobiliza\u00e7\u00e3o organizada por parlamentares e apoiadores do ex-presidente Jair Bolsonaro.<\/strong><\/p>\n<p style=\"text-align: justify;\">Na grava\u00e7\u00e3o, o parlamentar detalhou o deslocamento at\u00e9 o ponto de encontro do grupo e afirmou que a participa\u00e7\u00e3o do Acre no movimento \u00e9 simb\u00f3lica.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cA nossa caminhada pela liberdade, pela justi\u00e7a, junto com o N\u00edcolas, come\u00e7a aqui nesse momento. S\u00e3o quase meia-noite. Vamos embarcar agora de avi\u00e3o para Bras\u00edlia. S\u00e3o 3 mil quil\u00f4metros\u201d, disse.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Segundo ele, ap\u00f3s chegar \u00e0 capital federal, o grupo seguir\u00e1 por via terrestre at\u00e9 a cidade de Cristalina (GO), onde deve se encontrar com outros participantes da mobiliza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Ainda no v\u00eddeo, Coronel Ulysses destacou que o <strong>Acre n\u00e3o poderia ficar de fora do ato e relacionou a participa\u00e7\u00e3o do estado \u00e0 sua hist\u00f3ria. <\/strong><\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cO Acre n\u00e3o poderia jamais ficar fora dessa caminhada, porque o Acre \u00e9 um estado que lutou pra ser Brasil. N\u00f3s nunca nos acobardamos, sempre tivemos a coragem de lutar pelo Brasil melhor\u201d, afirmou.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">O deputado tamb\u00e9m citou um trecho do hino acreano ao defender o que chamou de luta pela liberdade e pela honra nacional.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cA liberdade \u00e9 um querido tesouro que depois de lutar nos seduz. E \u00e9 isso que n\u00f3s precisamos hoje pro nosso Brasil. Liberdade. N\u00f3s precisamos resgatar a honra da nossa na\u00e7\u00e3o\u201d, declarou, ao convocar apoiadores a acompanharem a mobiliza\u00e7\u00e3o.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>A caminhada foi iniciada pelo deputado federal Nikolas Ferreira (PL-MG), com a participa\u00e7\u00e3o de outros parlamentares e apoiadores.<\/strong> O grupo saiu de Paracatu (MG) com destino a Bras\u00edlia, em um percurso de aproximadamente 240 quil\u00f4metros, que deve ser conclu\u00eddo em cerca de sete dias, com <strong>previs\u00e3o de chegada \u00e0 capital federal no pr\u00f3ximo domingo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal Coronel Ulysses anunciou nesta quarta-feira (21), por meio de um v\u00eddeo publicado em suas redes sociais, que ir\u00e1 se juntar \u00e0 chamada \u201ccaminhada pela liberdade\u201d, mobiliza\u00e7\u00e3o organizada por parlamentares e apoiadores do ex-presidente Jair Bolsonaro. Na grava\u00e7\u00e3o, o parlamentar detalhou o deslocamento at\u00e9 o ponto de encontro do grupo e afirmou que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":169688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","jnews_video_option_group":[[]],"override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"Mobiliza\u00e7\u00e3o foi iniciada por Nikolas Ferreira e re\u00fane parlamentares e apoiadores"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"footnotes":""},"categories":[46],"tags":[],"class_list":["post-169687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro\" \/>\n<meta property=\"og:description\" content=\"Mobiliza\u00e7\u00e3o foi iniciada por Nikolas Ferreira e re\u00fane parlamentares e apoiadores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T16:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agazeta.Net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agazeta.Net\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/\",\"name\":\"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg\",\"datePublished\":\"2026-01-21T16:51:34+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg\",\"width\":800,\"height\":407,\"caption\":\"Foto: redes sociais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535\",\"name\":\"Agazeta.Net\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/agazeta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/","og_locale":"pt_BR","og_type":"article","og_title":"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro","og_description":"Mobiliza\u00e7\u00e3o foi iniciada por Nikolas Ferreira e re\u00fane parlamentares e apoiadores","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/","og_site_name":"Agazeta.net","article_published_time":"2026-01-21T16:51:34+00:00","og_image":[{"width":800,"height":407,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg","type":"image\/jpeg"}],"author":"Agazeta.Net","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agazeta.Net","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/","name":"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg","datePublished":"2026-01-21T16:51:34+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-21-at-11.42.56-AM.jpeg","width":800,"height":407,"caption":"Foto: redes sociais"},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/acre-nao-poderia-ficar-fora-ulysses-adere-a-caminhada-organizada-por-apoiadores-do-ex-presidente-bolsonaro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"\u201cAcre n\u00e3o poderia ficar fora\u201d: Ulysses adere \u00e0 caminhada organizada por apoiadores do ex-presidente Bolsonaro"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/2dc83e0a89887b90ba1bf51c99f14535","name":"Agazeta.Net","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/agazeta\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/169687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=169687"}],"version-history":[{"count":1,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/169687\/revisions"}],"predecessor-version":[{"id":169690,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/169687\/revisions\/169690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/169688"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=169687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=169687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=169687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}