{"id":169619,"date":"2026-01-20T10:34:58","date_gmt":"2026-01-20T15:34:58","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=169619"},"modified":"2026-01-20T10:34:58","modified_gmt":"2026-01-20T15:34:58","slug":"serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/","title":{"rendered":"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro"},"content":{"rendered":"<p style=\"text-align: justify;\">O senador pelo Acre M\u00e1rcio Bittar (PL) anunciou nesta ter\u00e7a-feira (20), por meio de um v\u00eddeo publicado em suas redes sociais, <strong>que ir\u00e1 se juntar \u00e0 chamada \u201ccaminhada pela liberdade\u201d,<\/strong> mobiliza\u00e7\u00e3o organizada por parlamentares e apoiadores do ex-presidente Jair Bolsonaro.<\/p>\n<p style=\"text-align: justify;\">Na publica\u00e7\u00e3o, <strong>Bittar afirmou que est\u00e1 \u201csomando for\u00e7as\u201d ao ato<\/strong>, que prev\u00ea um percurso entre cidades de Minas Gerais e Bras\u00edlia.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cEstou somando for\u00e7as na caminhada pela liberdade e anistia. Ser\u00e3o 200 km entre Minas e Bras\u00edlia, que demonstram a resist\u00eancia do povo brasileiro diante da tirania\u201d, declarou o senador.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Em outro trecho do v\u00eddeo, M\u00e1rcio Bittar disse que cancelou compromissos pessoais durante o recesso parlamentar para participar da mobiliza\u00e7\u00e3o.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cDo Acre, em nome do Brasil, eu cancelei as minhas viagens nesse m\u00eas de janeiro do recesso para participar com o deputado Nikolas Ferreira e v\u00e1rios outros colegas numa caminhada ao longo de 200 km em nome da liberdade dos presos pol\u00edticos do Brasil\u201d, afirmou.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Segundo o senador, o ato tem como objetivo defender a anistia do ex-presidente <strong>Jair Bolsonaro e de pessoas presas em decorr\u00eancia dos atos de 8 de janeiro, que ele classificou como \u201cpresos pol\u00edticos\u201d.<\/strong><\/p>\n<p style=\"text-align: justify;\">Bittar tamb\u00e9m afirmou que pretende levar simbolicamente \u00e0 mobiliza\u00e7\u00e3o a representa\u00e7\u00e3o do Acre.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cL\u00e1 do Acre, a terra que \u00e9 Brasil, por muita luta eu trago a esperan\u00e7a e a bravura do povo acreano para nos somar a outros parlamentares pol\u00edticos do Brasil inteiro nessa luta que s\u00f3 ter\u00e1 fim quando conseguirmos a anistia\u201d, disse, convidando seguidores a acompanhar o percurso.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>A mobiliza\u00e7\u00e3o foi iniciada pelo deputado federal Nikolas Ferreira (PL-MG)<\/strong>, acompanhado de outros pol\u00edticos e apoiadores, com sa\u00edda de Paracatu (MG) em dire\u00e7\u00e3o a Bras\u00edlia. O percurso, de aproximadamente 240 quil\u00f4metros, deve ser conclu\u00eddo em cerca de sete dias, <strong>com previs\u00e3o de chegada \u00e0 capital federal no pr\u00f3ximo domingo.<\/strong><\/p>\n<p style=\"text-align: justify;\">Nas redes sociais, Nikolas Ferreira definiu o ato como uma \u201ccaminhada pela liberdade e justi\u00e7a\u201d. <strong>O deputado comparou a mobiliza\u00e7\u00e3o \u00e0 marcha organizada pelo Movimento Brasil Livre (MBL) em 2016, durante o processo de impeachment da ex-presidente Dilma Rousseff<\/strong>, e afirmou que o objetivo \u00e9 \u201cromper o sil\u00eancio\u201d diante do que classifica como arbitrariedades judiciais e esc\u00e2ndalos do governo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O senador pelo Acre M\u00e1rcio Bittar (PL) anunciou nesta ter\u00e7a-feira (20), por meio de um v\u00eddeo publicado em suas redes sociais, que ir\u00e1 se juntar \u00e0 chamada \u201ccaminhada pela liberdade\u201d, mobiliza\u00e7\u00e3o organizada por parlamentares e apoiadores do ex-presidente Jair Bolsonaro. Na publica\u00e7\u00e3o, Bittar afirmou que est\u00e1 \u201csomando for\u00e7as\u201d ao ato, que prev\u00ea um percurso entre [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":169621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","jnews_video_option_group":[[]],"override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"Caminhada iniciada em Minas Gerais deve durar sete dias at\u00e9 a chegada \u00e0 capital federal"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"footnotes":""},"categories":[46],"tags":[152],"class_list":["post-169619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro\" \/>\n<meta property=\"og:description\" content=\"Caminhada iniciada em Minas Gerais deve durar sete dias at\u00e9 a chegada \u00e0 capital federal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T15:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danniely Avlis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danniely Avlis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/\",\"name\":\"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg\",\"datePublished\":\"2026-01-20T15:34:58+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg\",\"width\":800,\"height\":404,\"caption\":\"Foto: reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579\",\"name\":\"Danniely Avlis\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/danniely\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/","og_locale":"pt_BR","og_type":"article","og_title":"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro","og_description":"Caminhada iniciada em Minas Gerais deve durar sete dias at\u00e9 a chegada \u00e0 capital federal","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/","og_site_name":"Agazeta.net","article_published_time":"2026-01-20T15:34:58+00:00","og_image":[{"width":800,"height":404,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg","type":"image\/jpeg"}],"author":"Danniely Avlis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Danniely Avlis","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/","name":"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg","datePublished":"2026-01-20T15:34:58+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-20-at-10.25.00-AM.jpeg","width":800,"height":404,"caption":"Foto: reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/serao-200-km-em-nome-da-liberdade-diz-bittar-ao-aderir-a-caminhada-organizada-por-aliados-de-bolsonaro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"\u201cSer\u00e3o 200 km em nome da liberdade\u201d, diz Bittar ao aderir \u00e0 caminhada organizada por aliados de Bolsonaro"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/ab6e0ebcb997007c7e706b9cb30b3579","name":"Danniely Avlis","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/danniely\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/169619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=169619"}],"version-history":[{"count":1,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/169619\/revisions"}],"predecessor-version":[{"id":169623,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/169619\/revisions\/169623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/169621"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=169619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=169619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=169619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}