{"id":164406,"date":"2025-10-27T08:18:57","date_gmt":"2025-10-27T13:18:57","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=164406"},"modified":"2025-10-27T09:39:54","modified_gmt":"2025-10-27T14:39:54","slug":"recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/","title":{"rendered":"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco"},"content":{"rendered":"<p style=\"text-align: justify;\">O <a href=\"https:\/\/nk7-testes.com.br\/agazeta\/bebe-declarado-morto-acorda-durante-o-proprio-velorio-apos-13-horas-dentro-de-um-saco-em-rio-branco\/\">rec\u00e9m-nascido que havia despertado no pr\u00f3prio vel\u00f3rio ap\u00f3s ser declarado morto<\/a> na Maternidade B\u00e1rbara Heliodora, no \u00faltimo s\u00e1bado (25), em Rio Branco, <strong>n\u00e3o resistiu e faleceu na noite deste domingo (26)<\/strong>, por volta das 23h. Em nota, a Secretaria de Sa\u00fade do Estado (Sesacre), lamenta a morte do beb\u00ea.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">&#8220;A Secretaria de Estado de Sa\u00fade do Acre (Sesacre), por meio da dire\u00e7\u00e3o da Maternidade B\u00e1rbara Heliodora, comunica, com profundo pesar, o falecimento do rec\u00e9m-nascido atendido na unidade (ap\u00f3s ter apresentado sinais vitais, depois de declarado \u00f3bito), ocorrido \u00e0s 23h15 de domingo, 26 de outubro, em decorr\u00eancia de um quadro de choque s\u00e9ptico e sepse neonatal&#8221;, diz a nota.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">O beb\u00ea havia nascido prematuro, com 23 semanas de gesta\u00e7\u00e3o, por volta das 21h de sexta-feira (24), logo foi constatado o \u00f3bito. <strong>Enquanto acontecia o vel\u00f3rio na manh\u00e3 de s\u00e1bado (25),<\/strong> a tia ouviu o choro do beb\u00ea, que foi levado de volta para a maternidade.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/nk7-testes.com.br\/agazeta\/medica-detalha-atendimento-de-bebe-prematuro-que-voltou-a-apresentar-sinais-de-vida-apos-ser-declarado-morto\/\">Em coletiva realizada na tarde de s\u00e1bado, a m\u00e9dica neonatologista Mariana Colodett,<\/a> respons\u00e1vel pelo atendimento do\u00a0rec\u00e9m-nascido, informou que <strong>em raz\u00e3o da prematuridade extrema<\/strong>, o caso era grave, por\u00e9m est\u00e1vel, at\u00e9 aquele momento.<\/p>\n<p style=\"text-align: justify;\">Os pais do beb\u00ea s\u00e3o residentes do munic\u00edpio de Pauini, no Amazonas, e <strong>estavam em Rio Branco desde quinta-feira (23)<\/strong>. Na nota, a Sesacre expressa solidariedade aos familiares:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">&#8220;Neste momento de imensa dor, expressamos nossa solidariedade e respeito \u00e0 m\u00e3e, ao pai e a todos os familiares, desejando que encontrem conforto e acolhimento diante dessa perda irrepar\u00e1vel&#8221;, diz a nota.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">O Minist\u00e9rio P\u00fablico do Acre (MPAC), acompanha o caso e diz que vai adotar todas as provid\u00eancias cab\u00edveis para apurar as responsabilidades. A equipe m\u00e9dica respons\u00e1vel pela constata\u00e7\u00e3o do \u00f3bito do beb\u00ea tamb\u00e9m foi afastada pelo governo do Acre.<\/p>\n<h4>Confira a nota da Sesacre na \u00edntegra:<\/h4>\n<p style=\"text-align: justify;\"><em>A Secretaria de Estado de Sa\u00fade do Acre (Sesacre), por meio da dire\u00e7\u00e3o da Maternidade B\u00e1rbara Heliodora, comunica, com profundo pesar, o falecimento do rec\u00e9m-nascido atendido na unidade (<strong>ap\u00f3s ter apresentado sinais vitais, depois de declarado \u00f3bito<\/strong>), ocorrido \u00e0s 23h15 de domingo, 26 de outubro, em decorr\u00eancia de um quadro de choque s\u00e9ptico e sepse neonatal.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Neste momento de imensa dor, expressamos nossa solidariedade e respeito \u00e0 m\u00e3e, ao pai e a todos os familiares, desejando que encontrem conforto e acolhimento diante dessa perda irrepar\u00e1vel.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>Todos os esfor\u00e7os poss\u00edveis foram realizados para garantir o melhor cuidado e suporte durante todo o per\u00edodo de interna\u00e7\u00e3o<\/strong>. Refor\u00e7amos que, devido \u00e0 prematuridade extrema do beb\u00ea, a transfer\u00eancia para outra unidade n\u00e3o chegou a ser cogitada pela equipe m\u00e9dica, diante do alto risco de agravamento do quadro.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>O caso est\u00e1 sendo rigorosamente apurado, e a equipe respons\u00e1vel pelo atendimento inicial foi afastada para assegurar a lisura de todo o processo.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>A Sesacre e a equipe da maternidade lamentam profundamente o desfecho e reafirmam seu compromisso de redobrar o olhar e seguir aprimorando, a cada dia, o cuidado e a aten\u00e7\u00e3o humanizada \u00e0 vida.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O rec\u00e9m-nascido que havia despertado no pr\u00f3prio vel\u00f3rio ap\u00f3s ser declarado morto na Maternidade B\u00e1rbara Heliodora, no \u00faltimo s\u00e1bado (25), em Rio Branco, n\u00e3o resistiu e faleceu na noite deste domingo (26), por volta das 23h. Em nota, a Secretaria de Sa\u00fade do Estado (Sesacre), lamenta a morte do beb\u00ea. &#8220;A Secretaria de Estado de [&hellip;]<\/p>\n","protected":false},"author":2671,"featured_media":164357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","jnews_video_option_group":[[]],"override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"O beb\u00ea havia nascido prematuro, com 23 semanas de gesta\u00e7\u00e3o, por volta das 21h de sexta-feira (24), logo foi constatado o \u00f3bito"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"footnotes":""},"categories":[54],"tags":[152],"class_list":["post-164406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","tag-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco\" \/>\n<meta property=\"og:description\" content=\"O beb\u00ea havia nascido prematuro, com 23 semanas de gesta\u00e7\u00e3o, por volta das 21h de sexta-feira (24), logo foi constatado o \u00f3bito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T13:18:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T14:39:54+00:00\" \/>\n<meta name=\"author\" content=\"Natalia Lindoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia Lindoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/\",\"name\":\"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/10\/Design-sem-nome.svg\",\"datePublished\":\"2025-10-27T13:18:57+00:00\",\"dateModified\":\"2025-10-27T14:39:54+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/1584115848551faee02df362e8a5f628\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/10\/Design-sem-nome.svg\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/10\/Design-sem-nome.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/1584115848551faee02df362e8a5f628\",\"name\":\"Natalia Lindoso\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/natalia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/","og_locale":"pt_BR","og_type":"article","og_title":"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco","og_description":"O beb\u00ea havia nascido prematuro, com 23 semanas de gesta\u00e7\u00e3o, por volta das 21h de sexta-feira (24), logo foi constatado o \u00f3bito","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/","og_site_name":"Agazeta.net","article_published_time":"2025-10-27T13:18:57+00:00","article_modified_time":"2025-10-27T14:39:54+00:00","author":"Natalia Lindoso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Natalia Lindoso","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/","name":"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/10\/Design-sem-nome.svg","datePublished":"2025-10-27T13:18:57+00:00","dateModified":"2025-10-27T14:39:54+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/1584115848551faee02df362e8a5f628"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/10\/Design-sem-nome.svg","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/10\/Design-sem-nome.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/recem-nascido-que-despertou-apos-ser-declarado-morto-nao-resiste-e-morre-em-rio-branco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"Rec\u00e9m-nascido que despertou ap\u00f3s ser declarado morto n\u00e3o resiste e morre em Rio Branco"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/1584115848551faee02df362e8a5f628","name":"Natalia Lindoso","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/natalia\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/164406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/2671"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=164406"}],"version-history":[{"count":3,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/164406\/revisions"}],"predecessor-version":[{"id":164412,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/164406\/revisions\/164412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/164357"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=164406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=164406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=164406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}