{"id":160442,"date":"2025-08-31T14:20:11","date_gmt":"2025-08-31T19:20:11","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=160442"},"modified":"2025-08-31T14:20:11","modified_gmt":"2025-08-31T19:20:11","slug":"o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/","title":{"rendered":"O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Com o olhar de vanguarda da perfumaria nacional, <\/span><b>O Botic\u00e1rio<\/b><span style=\"font-weight: 400;\"> surpreende novamente com a nova fragr\u00e2ncia <\/span><b>EGEO CoguMellow<\/b><span style=\"font-weight: 400;\">, que traz para o mercado um novo gourmand com o <\/span><b>cogumelo Boletus Edulis*<\/b><span style=\"font-weight: 400;\">, ingrediente in\u00e9dito da perfumaria. A novidade chega para duplar com a primeira vers\u00e3o da linha, EGEO Cogu, que surpreendeu os consumidores e gerou curiosidade dos lovers da marca para conhecerem o olfativo in\u00e9dito da perfumaria no mundo.\u00a0<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-weight: 400;\">**<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Egeo CoguMellow<\/b><span style=\"font-weight: 400;\"> \u00e9 um frutal gourmand que surpreende na combina\u00e7\u00e3o das notas de destaque: smoothie de p\u00eara e baunilha de madagascar com o acorde de cogumelo, enquanto <\/span><b>Egeo Cogu<\/b><span style=\"font-weight: 400;\">, um oriental frutal de notas gourmands e amadeiradas, com amora e cr\u00e8me brull\u00e8 e o acorde de cogumelo com grande presen\u00e7a. A novidade \u00e9 mais frutal e ideal para o dia a dia, enquanto a outra vers\u00e3o tem a pot\u00eancia do gourmand mais sofisticado.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-160445\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1.jpg\" alt=\"\" width=\"1377\" height=\"912\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1.jpg 1377w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1-300x199.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1-1024x678.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1-768x509.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1-750x497.jpg 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-2-1-1140x755.jpg 1140w\" sizes=\"(max-width: 1377px) 100vw, 1377px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">As duas vers\u00f5es de fragr\u00e2ncias com o <\/span><b>exclusivo acorde de cogumelo<\/b><span style=\"font-weight: 400;\"> e assinaturas olfativas desenvolvidas pela renomada casa de fragr\u00e2ncias alem\u00e3, Symrise, chegam ao consumidor com mais uma inova\u00e7\u00e3o da proposta de <\/span><b>layering, t\u00e9cnica de sobreposi\u00e7\u00e3o na perfumaria<\/b><span style=\"font-weight: 400;\"> que permite a combina\u00e7\u00e3o no uso. <\/span><b>EGEO CoguMellow e Cogu<\/b><span style=\"font-weight: 400;\"> est\u00e3o dispon\u00edveis em edi\u00e7\u00e3o limitada, com 10% de desconto at\u00e9 o dia 31 de agosto<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><b>O Botic\u00e1rio traz Zaad Intense em nova vers\u00e3o mais potente de cl\u00e1ssico da marca<\/b><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-160444\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1.jpg\" alt=\"\" width=\"1208\" height=\"702\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1.jpg 1208w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1-300x174.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1-1024x595.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1-768x446.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1-750x436.jpg 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-3-1-1140x662.jpg 1140w\" sizes=\"(max-width: 1208px) 100vw, 1208px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Zaad Intense, do Botic\u00e1rio, acaba de chegar ao portf\u00f3lio de perfumaria masculina da marca, <\/span><b>inspirado na travessia do Cabo Horn<\/b><span style=\"font-weight: 400;\">, no Chile, uma das rotas mais desafiadoras e lend\u00e1rias para os navegantes. A fragr\u00e2ncia \u00e9 <\/span><b>a vers\u00e3o mais potente de Zaad Tradicional, <\/b><span style=\"font-weight: 400;\">revelando uma vers\u00e3o mais intensa do DNA ic\u00f4nico da marca. Ela tamb\u00e9m<\/span><b> conta com o exclusivo Acorde Driftwood<\/b><span style=\"font-weight: 400;\">, inspirado na madeira flutuante, que agrega notas amadeiradas, sofistica\u00e7\u00e3o e complexidade olfativa a ela, traduzindo a for\u00e7a e a intensidade do esp\u00edrito destemido do explorador moderno.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">**<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Al\u00e9m disso, o eau de parfum traz consigo a <\/span><b>tecnologia Thalassogaia<\/b><span style=\"font-weight: 400;\">, que mimetiza o ecossistema oce\u00e2nico e o traduz olfativamente, trazendo seus atributos e mantendo o tom aqu\u00e1tico da linha, enquanto proporciona robustez a uma fragr\u00e2ncia genuinamente amadeirada e arom\u00e1tica, com elementos de diferencia\u00e7\u00e3o desejados pelo consumidor.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">**<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O lan\u00e7amento eleva Zaad a um novo patamar, fortalecendo a atua\u00e7\u00e3o do Botic\u00e1rio na perfumaria masculina, com intensidade olfativa e atributos de sofistica\u00e7\u00e3o para os amadeirados. Para materializar essa intensidade, a narrativa que atua como plano de fundo e inspira\u00e7\u00e3o para a cria\u00e7\u00e3o da fragr\u00e2ncia alcan\u00e7a o \u00e1pice do esp\u00edrito desbravador e aventureiro, caracter\u00edsticos de Zaad, por meio da liga\u00e7\u00e3o com o mar impetuoso que est\u00e1 conectado a esse homem e, ao mesmo tempo, o desafia.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Intensidade em cada camada da pir\u00e2mide olfativa<\/b><\/p>\n<p style=\"text-align: justify;\"><b>Zaad Intense<\/b><span style=\"font-weight: 400;\"> tem em suas notas de topo a <\/span><b>Bergamota da It\u00e1lia, Coriandro da R\u00fassia, Zimbro, Cardamomo, Notas Verdes e Pimenta Rosa<\/b><span style=\"font-weight: 400;\">. No corpo, <\/span><b>Cedro dos Estados Unidos, Cravo, Noz Moscada da Indon\u00e9sia e Patchouli da Indon\u00e9sia<\/b><span style=\"font-weight: 400;\">. Em seu desfecho, as notas de fundo se projetam com<\/span><b> \u00c2mbar, Musgo de Carvalho, Notas Oz\u00f4nicas, S\u00e2ndalo da Austr\u00e1lia, Vetiver e o Acorde Driftwoods.<\/b><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><b>O Botic\u00e1rio acelera estrat\u00e9gia de refis e projeta crescimento de vendas<\/b><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-160447\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-4.png\" alt=\"\" width=\"517\" height=\"373\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-4.png 517w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-4-300x216.png 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-4-120x86.png 120w\" sizes=\"(max-width: 517px) 100vw, 517px\" \/><\/p>\n<p style=\"text-align: justify;\"><b>O Botic\u00e1rio<\/b><span style=\"font-weight: 400;\">, marca de beleza mais amada e preferida do Brasil, refor\u00e7a seu compromisso com o meio ambiente e a sociedade ao consolidar a cada ano sua aposta em refis como parte de uma estrat\u00e9gia que vai al\u00e9m do consumo. O crescente interesse dos consumidores por alternativas mais sustent\u00e1veis impulsiona um movimento positivo para toda a cadeia produtiva e tem performado acima do esperado no varejo. A campanha promocional vem se superando anualmente, mas em 2025, direcionou um indicador positivo materializando essa tend\u00eancia ao observar uma performance <\/span><b>105% acima da meta j\u00e1 na primeira quinzena de resultados<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">**<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A demanda e o interesse do consumidor por refis aparecem com clareza nas buscas e representa uma tend\u00eancia positiva n\u00e3o apenas para a cadeia produtiva, do ponto de vista ESG, mas tamb\u00e9m como tra\u00e7\u00e3o no varejo. Foram mais de <\/span><b>801 mil pesquisas por \u201crefis\u201d no e-commerce oficial do Botic\u00e1rio<\/b><span style=\"font-weight: 400;\"> de janeiro \u00e0 primeira semana de agosto.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">**<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">No digital, os consumidores j\u00e1 elegeram seus best sellers: com mec\u00e2nica <\/span><b>\u201ccompre e leve refil\u201d<\/b><span style=\"font-weight: 400;\">, os mais comprados s\u00e3o <\/span><b>Hidratante Nativa Spa de Ameixa Negra 400ml, Ameixa 400ml, Uva Merlot 400ml, Orqu\u00eddea Noire 400ml e Cuide-se Bem Deleite 400ml<\/b><span style=\"font-weight: 400;\">. Al\u00e9m do resultado positivo no varejo desde 2021, a estrat\u00e9gia de refis refor\u00e7a amparado na efici\u00eancia em usos de recursos e custos na cadeia. Na linha Nativa SPA, um refil de 350 ml utiliza 78% menos pl\u00e1stico do que a embalagem regular de 400 ml. A marca estima que a escolha por refis evita cerca de 280 toneladas de res\u00edduos por ano, com integra\u00e7\u00e3o ao Boti Recicla, programa que recolhe embalagens de qualquer marca e as destina a cooperativas parceiras \u2014 iniciativas que reduzem desperd\u00edcio, preservam margens e refor\u00e7am reputa\u00e7\u00e3o junto a consumidores e franqueados. As ofertas de refis seguem at\u00e9 *31 de agosto de 2025*, com disponibilidade limitada, em todas as lojas f\u00edsicas, e-commerce e aplicativo.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Com o olhar de vanguarda da perfumaria nacional, O Botic\u00e1rio surpreende novamente com a nova fragr\u00e2ncia EGEO CoguMellow, que traz para o mercado um novo gourmand com o cogumelo Boletus Edulis*, ingrediente in\u00e9dito da perfumaria. A novidade chega para duplar com a primeira vers\u00e3o da linha, EGEO Cogu, que surpreendeu os consumidores e gerou curiosidade [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":160446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","jnews_video_option_group":[[]],"override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"footnotes":""},"categories":[82],"tags":[],"class_list":["post-160442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gazeta-estilo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espet\u00e1culo do Amap\u00e1, que reflete sobre a Amaz\u00f4nia contempor\u00e2nea, se apresenta em Rio Branco\" \/>\n<meta property=\"og:description\" content=\"O espet\u00e1culo busca sensibilizar o p\u00fablico para um movimento de reflex\u00e3o pol\u00edtica, abordando de forma cr\u00edtica alguns temas que s\u00e3o urgentes e atuais para a Amaz\u00f4nia, como os problemas sociais, ecol\u00f3gicos e urban\u00edsticos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-31T19:20:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ascom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Espet\u00e1culo do Amap\u00e1, que reflete sobre a Amaz\u00f4nia contempor\u00e2nea, se apresenta em Rio Branco\" \/>\n<meta name=\"twitter:description\" content=\"O espet\u00e1culo busca sensibilizar o p\u00fablico para um movimento de reflex\u00e3o pol\u00edtica, abordando de forma cr\u00edtica alguns temas que s\u00e3o urgentes e atuais para a Amaz\u00f4nia, como os problemas sociais, ecol\u00f3gicos e urban\u00edsticos\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ascom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/\",\"name\":\"O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg\",\"datePublished\":\"2025-08-31T19:20:11+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/81a23297bc9b9feb1f01900cbe29036e\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/81a23297bc9b9feb1f01900cbe29036e\",\"name\":\"Ascom\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/ascom\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/","og_locale":"pt_BR","og_type":"article","og_title":"Espet\u00e1culo do Amap\u00e1, que reflete sobre a Amaz\u00f4nia contempor\u00e2nea, se apresenta em Rio Branco","og_description":"O espet\u00e1culo busca sensibilizar o p\u00fablico para um movimento de reflex\u00e3o pol\u00edtica, abordando de forma cr\u00edtica alguns temas que s\u00e3o urgentes e atuais para a Amaz\u00f4nia, como os problemas sociais, ecol\u00f3gicos e urban\u00edsticos","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/","og_site_name":"Agazeta.net","article_published_time":"2025-08-31T19:20:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg","type":"image\/jpeg"}],"author":"Ascom","twitter_card":"summary_large_image","twitter_title":"Espet\u00e1culo do Amap\u00e1, que reflete sobre a Amaz\u00f4nia contempor\u00e2nea, se apresenta em Rio Branco","twitter_description":"O espet\u00e1culo busca sensibilizar o p\u00fablico para um movimento de reflex\u00e3o pol\u00edtica, abordando de forma cr\u00edtica alguns temas que s\u00e3o urgentes e atuais para a Amaz\u00f4nia, como os problemas sociais, ecol\u00f3gicos e urban\u00edsticos","twitter_image":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg","twitter_misc":{"Escrito por":"Ascom","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/","name":"O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg","datePublished":"2025-08-31T19:20:11+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/81a23297bc9b9feb1f01900cbe29036e"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/08\/Foto-1-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/o-boticario-apresenta-egeo-cogumellow-nova-versao-da-primeira-fragrancia-do-mundo-a-utilizar-o-cogumelo-boletus-edulis-em-sua-composicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"O Botic\u00e1rio apresenta EGEO CoguMellow, nova vers\u00e3o da primeira fragr\u00e2ncia do mundo a utilizar o cogumelo Boletus Edulis em sua composi\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/81a23297bc9b9feb1f01900cbe29036e","name":"Ascom","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/ascom\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/160442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=160442"}],"version-history":[{"count":0,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/160442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/160446"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=160442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=160442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=160442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}