{"id":152816,"date":"2025-04-14T17:36:26","date_gmt":"2025-04-14T22:36:26","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=152816"},"modified":"2025-04-14T17:36:26","modified_gmt":"2025-04-14T22:36:26","slug":"coluna-jackie-13-04-2025","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/","title":{"rendered":"COLUNA JACKIE \u2013 13\/04\/2025"},"content":{"rendered":"<h2><b>Simone recebe o acreano durante almo\u00e7o no Fasano, em S\u00e3o Paulo<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152818\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1.jpeg\" alt=\"\" width=\"1049\" height=\"1061\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1.jpeg 1049w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1-297x300.jpeg 297w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1-1012x1024.jpeg 1012w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1-768x777.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1-75x75.jpeg 75w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-1-750x759.jpeg 750w\" sizes=\"(max-width: 1049px) 100vw, 1049px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O jornalista acreano <\/span><b>Nostradamus Fran\u00e7a<\/b><span style=\"font-weight: 400;\">, que hoje reside em S\u00e3o Paulo, tem uma hist\u00f3ria interessante que o liga \u00e0 cantora Simone Bittencourt de Oliveira, a <\/span><b>Simone<\/b><span style=\"font-weight: 400;\">. Ele nasceu no dia 25 de dezembro e o hit da cantora \u201cEnt\u00e3o \u00e9 Natal\u201d embalou muitas de suas celebra\u00e7\u00f5es. Ao tomar conhecimento da hist\u00f3ria do acreano, a produ\u00e7\u00e3o da cantora o convidou para o show \u201cSimone\u201d, ocorrido no Tokio Marine Hall, dia 22 de mar\u00e7o. No dia seguinte, Simone o recebeu durante o almo\u00e7o no restaurante Fasano, pouco antes de embarcar para o pr\u00f3ximo show de sua turn\u00ea. Um momento que ficou registrado para o jornalista, que sempre foi f\u00e3 da artista.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A cantora este em turn\u00ea novamente, dois anos ap\u00f3s a turn\u00ea \u201cT\u00f4 voltando\u201d em que comemorou as cinco d\u00e9cadas de carreira. Os \u00faltimos anos foram de pura celebra\u00e7\u00e3o para Simone: mais de 50 anos de carreira comemorados em uma turn\u00ea de sucesso, um pr\u00eamio e homenagem no Grammy Latino 2023 e seu retorno aos em festivais de m\u00fasica. A artista, est\u00e1 melhor do que nunca, aos 75 anos de idade.\u00a0<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Matheus Boa Sorte esteve no Acre no in\u00edcio de abril<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152819\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-2.jpeg\" alt=\"\" width=\"1052\" height=\"915\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-2.jpeg 1052w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-2-300x261.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-2-1024x891.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-2-768x668.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-2-750x652.jpeg 750w\" sizes=\"(max-width: 1052px) 100vw, 1052px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O jornalista e youtuber <\/span><b>Matheus Boa Sorte<\/b><span style=\"font-weight: 400;\">, apresentador do programa Boa Sorte Viajante\u00a0esteve em Rio Branco no in\u00edcio de abril e aqui ficou hospedado no Aquiri Hostel, tendo como anfitri\u00f5es os queridos <\/span><b>Naldo<\/b><span style=\"font-weight: 400;\"> e <\/span><b>B\u00e1rbara<\/b> <b>Huberty<\/b><span style=\"font-weight: 400;\">. Com mais de 600 mil seguidores no Youtube, ele veio acompanhado pelo rep\u00f3rter cinematogr\u00e1fico <\/span><b>Rodrigo Freitas<\/b><span style=\"font-weight: 400;\">, o M\u00e3ozinha,\u00a0para gravar uma s\u00e9rie de reportagens sobre pontos tur\u00edsticos locais, que ir\u00e3o ao ar a partir de agosto. O conte\u00fado estar\u00e1 tamb\u00e9m na TV Brasil e no Travel Box Brasil. Na foto, a dupla com a B\u00e1rbara e Gleison Xavier.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Festa beneficente para celebrar o anivers\u00e1rio do governador Gladson Cameli<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152820\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-3.jpeg\" alt=\"\" width=\"1095\" height=\"728\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-3.jpeg 1095w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-3-300x199.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-3-1024x681.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-3-768x511.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-3-750x499.jpeg 750w\" sizes=\"(max-width: 1095px) 100vw, 1095px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Amigos e familiares de <\/span><b>Gladson<\/b> <b>Camel\u00ed<\/b><span style=\"font-weight: 400;\">, se reuniram no dia 30 de mar\u00e7o, para um almo\u00e7o beneficente, no Buffet AFA Jardim em celebra\u00e7\u00e3o aos 47 anos de vida do governador. A pedido do aniversariante, todos os convidados contribu\u00edram com leite em p\u00f3, fraldas descart\u00e1veis e sacol\u00f5es que foram doados a institui\u00e7\u00f5es que cuidam de pessoas em situa\u00e7\u00e3o de vulnerabilidades social. As fotos s\u00e3o de Jos\u00e9 Caminha.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152821\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-4.jpeg\" alt=\"\" width=\"1124\" height=\"778\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-4.jpeg 1124w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-4-300x208.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-4-1024x709.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-4-768x532.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-4-750x519.jpeg 750w\" sizes=\"(max-width: 1124px) 100vw, 1124px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O aniversariante com a vice-governadora Mailza Assis<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152822\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg\" alt=\"\" width=\"1191\" height=\"788\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg 1191w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5-300x198.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5-1024x678.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5-768x508.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5-750x496.jpeg 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5-1140x754.jpeg 1140w\" sizes=\"(max-width: 1191px) 100vw, 1191px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O abra\u00e7o amigo da secret\u00e1ria de Comunica\u00e7\u00e3o Nayara Lessa<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152823\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-6.jpeg\" alt=\"\" width=\"1095\" height=\"742\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-6.jpeg 1095w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-6-300x203.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-6-1024x694.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-6-768x520.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-6-750x508.jpeg 750w\" sizes=\"(max-width: 1095px) 100vw, 1095px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O secret\u00e1rio estadual de Ind\u00fastria, Ci\u00eancia e Tecnologia, Assur\u00a0Mesquita, e o presidente da Fieac Jos\u00e9 Adriano, prestigiaram o Governador do Acre<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152824\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-7.jpeg\" alt=\"\" width=\"1041\" height=\"694\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-7.jpeg 1041w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-7-300x200.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-7-1024x683.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-7-768x512.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-7-750x500.jpeg 750w\" sizes=\"(max-width: 1041px) 100vw, 1041px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Francisco Gomes, o Chico Gat\u00e3o, representante do Gabinete do Governador no Juru\u00e1, veio de Cruzeiro do Sul para participar do almo\u00e7o<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Celebra\u00e7\u00e3o ancestral no cora\u00e7\u00e3o da floresta<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152825\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-8.jpeg\" alt=\"\" width=\"870\" height=\"1080\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-8.jpeg 870w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-8-242x300.jpeg 242w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-8-825x1024.jpeg 825w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-8-768x953.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-8-750x931.jpeg 750w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">De 12 a 16 de julho, a Aldeia Mutum, no munic\u00edpio de Tarauac\u00e1 (AC), ser\u00e1 o cen\u00e1rio do <\/span><i><span style=\"font-weight: 400;\">Festival Mariri Yawanawa 2025<\/span><\/i><span style=\"font-weight: 400;\"> \u2014 uma imers\u00e3o profunda na cultura, espiritualidade e arte do Povo Yawanawa. Caciques, paj\u00e9s, cantores e artistas das diversas aldeias se re\u00fanem para uma semana de cerim\u00f4nias, dan\u00e7as, cantos e celebra\u00e7\u00e3o da for\u00e7a ancestral. Como diz o cacique geral do povo Yawanawa, Tashka Yawanawa: \u201c\u00c9 tempo de despertar e recordar nossos valores culturais e espirituais\u201d. A realiza\u00e7\u00e3o \u00e9 da Associa\u00e7\u00e3o Sociocultural Yawanawa.<\/span><\/p>\n<p style=\"text-align: left;\">\n<p><b>Mil p\u00e9s dan\u00e7ando, mil vozes ecoando<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O <\/span><i><span style=\"font-weight: 400;\">Mariri Yawanawa<\/span><\/i><span style=\"font-weight: 400;\"> \u00e9 mais que um festival \u2014 \u00e9 um reencontro com a alma da floresta. Realizado na Aldeia Mutum, a festa re\u00fane o Povo da Queixada em rituais de cura, brincadeiras, cantos e dan\u00e7as que atravessam o tempo. Lideran\u00e7as como o cacique e l\u00edder espiritual Matsini, a paj\u00e9 Hushahu e o jovem cacique e l\u00edder espiritual Rasu mant\u00eam vivo o legado deixado pelo inesquec\u00edvel <\/span><b>Paj\u00e9 Tata<\/b><span style=\"font-weight: 400;\">. Um convite para ouvir o chamado da floresta. Tashka Yawanawa afirma que durante o Mariri ter\u00e3o mais de mil p\u00e9s dan\u00e7ando e mais de mil vozes ecoando. Informa\u00e7\u00f5es no Instagram @maririyawanawa.oficial e com Renata Reluz (68) 99916-1000.<\/span><\/p>\n<h2 style=\"text-align: left;\">\n<p><b>Procuradora de justi\u00e7a Patr\u00edcia R\u00eago recebe Diploma Bertha Luz<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152826\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-9.jpeg\" alt=\"\" width=\"1053\" height=\"706\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-9.jpeg 1053w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-9-300x201.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-9-1024x687.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-9-768x515.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-9-750x503.jpeg 750w\" sizes=\"(max-width: 1053px) 100vw, 1053px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Parab\u00e9ns para a procuradora de Justi\u00e7a do Minist\u00e9rio P\u00fablico do Estado do Acre (MPAC), <\/span><b>Patr\u00edcia de Amorim R\u00eago<\/b><span style=\"font-weight: 400;\">, que recebeu no dia 27 de mar\u00e7o, em Bras\u00edlia, o Diploma Bertha Lutz, uma das mais importantes honrarias concedidas pelo Senado Federal. A cerim\u00f4nia ocorreu no plen\u00e1rio e homenageou 19 personalidades.<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A indica\u00e7\u00e3o, feita pelo senador <\/span><b>S\u00e9rgio Petec\u00e3o<\/b><span style=\"font-weight: 400;\">, reconhece a atua\u00e7\u00e3o da procuradora na defesa dos direitos das mulheres e na promo\u00e7\u00e3o da igualdade de g\u00eanero no Brasil. A procuradora recebeu a honraria das m\u00e3os da conselheira do Tribunal de Contas do Estado do Acre, <\/span><b>Naluh Gouveia<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Cau Bartholo lan\u00e7a o remix oficial de A R\u00e3, m\u00fasica de Jo\u00e3o Donato<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152827\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-10.jpeg\" alt=\"\" width=\"992\" height=\"864\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-10.jpeg 992w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-10-300x261.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-10-768x669.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-10-750x653.jpeg 750w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Mais um momento marcante na carreira da <\/span><b>DJ Cau Bartholo<\/b><span style=\"font-weight: 400;\">! Ela lan\u00e7ou com muito barulho nesta semana, pela Universal Music, o remix oficial de \u201cA R\u00e3\u201d, cl\u00e1ssico do conterr\u00e2neo <\/span><b>Jo\u00e3o Donato<\/b><span style=\"font-weight: 400;\">, em parceria com o grande produtor <\/span><b>Zeo Guinle.<\/b><span style=\"font-weight: 400;\"> A faixa j\u00e1 est\u00e1 dispon\u00edvel em todas as plataformas digitais.<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A artista acreana assina, oficialmente, a releitura de uma das m\u00fasicas mais ic\u00f4nicas da Bossa Nova, com a apoio da fam\u00edlia Donato \u2013 sua esposa <\/span><b>Ivone Bel\u00e9m <\/b><span style=\"font-weight: 400;\">e o filho <\/span><b>Donatinho<\/b><span style=\"font-weight: 400;\"> &#8211; e a chancela de uma das maiores gravadoras do mundo. O remix mant\u00e9m o vocal de Donato, com batidas vibrantes de Deep House.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Meyre Manaus realizou mais um Miss e Mister Mirim Universo com sucesso<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152828\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-11.jpeg\" alt=\"\" width=\"1080\" height=\"848\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-11.jpeg 1080w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-11-300x236.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-11-1024x804.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-11-768x603.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-11-750x589.jpeg 750w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Refer\u00eancia em concursos de beleza, a promoter <\/span><b>Meyre Manaus<\/b><span style=\"font-weight: 400;\"> realizou no domingo, 13, no Gran Reserva, a grande final do <\/span><b>Concurso Miss e Mister Mirim Universo<\/b><span style=\"font-weight: 400;\">. Em breve, os representantes acreanos estar\u00e3o brilhando nas passarelas nacionais. Na foto, <\/span><b>Meyre Manaus <\/b><span style=\"font-weight: 400;\">com os jurados: as jornalistas <\/span><b>Aline Rocha <\/b><span style=\"font-weight: 400;\">e<\/span><b> Degeane Santos<\/b><span style=\"font-weight: 400;\">, as misses <\/span><b>Beatriz Almeida<\/b><span style=\"font-weight: 400;\"> e <\/span><b>Clara Correia<\/b><span style=\"font-weight: 400;\"> e o Mister Acre <\/span><b>Kayk Amorim<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>C\u00e9sar J\u00fanior celebra o sucesso da nova temporada de Dona Helena\u00a0<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152829\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-12.jpeg\" alt=\"\" width=\"992\" height=\"521\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-12.jpeg 992w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-12-300x158.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-12-768x403.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-12-750x394.jpeg 750w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Parab\u00e9ns ao ator, produtor e diretor teatral<\/span><b> C\u00e9sar J\u00fanior<\/b><span style=\"font-weight: 400;\"> pela nova temporada de <\/span><b>Dona Helena &#8211; A Pe\u00e7a<\/b><span style=\"font-weight: 400;\">, que esteve em cartaz no Teatro de Arena do Sesc de 8 a 11 de abril, com reflex\u00f5es sobre sa\u00fade mental e empatia.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">*<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No dia 10 de abril, os psic\u00f3logos <\/span><b>Carolina Carvalho de Souza <\/b><span style=\"font-weight: 400;\">e <\/span><b>Jonsos Nunes J\u00fanior<\/b><span style=\"font-weight: 400;\"> comandaram um bate-papo com a plateia. O espet\u00e1culo foi financiado pela Lei Paulo Gustavo (LPG), por meio do Governo Federal e do Governo do Estado do Acre, via Funda\u00e7\u00e3o de Cultura Elias Mansour (FEM), SESC Acre e apoio local das empresas Made In Acre, Rastreacre, Studio F\u00e1bio e Miragina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O ator com a sua equipe: o fot\u00f3grafo Marcelo Dagnoni, a int\u00e9rprete de libras Ju Bernardino, a assessora de imprensa Jackie Pinheiro, o assistente de produ\u00e7\u00e3o Murilo Augusto e o iluminador Luiz Rabic\u00f3<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Jornada Jovem da Administra\u00e7\u00e3o<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152831\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-14.jpeg\" alt=\"\" width=\"934\" height=\"1083\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-14.jpeg 934w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-14-259x300.jpeg 259w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-14-883x1024.jpeg 883w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-14-768x891.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-14-750x870.jpeg 750w\" sizes=\"(max-width: 934px) 100vw, 934px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Na pr\u00f3xima ter\u00e7a-feira, 15, o Hotel Nobile ser\u00e1 palco da <\/span><b>Jornada Jovem da Administra\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\">, um evento que reunir\u00e1 estudantes, profissionais da \u00e1rea, institui\u00e7\u00f5es de ensino e setores produtivos para discutir os desafios e oportunidades no campo da administra\u00e7\u00e3o. A iniciativa busca promover o protagonismo juvenil, estimular o pensamento cr\u00edtico e aproximar teoria e pr\u00e1tica em um ambiente de troca e inspira\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A Chef <\/span><b>Rafysa Assem <\/b><span style=\"font-weight: 400;\">estar\u00e1 no evento representando o rec\u00e9m inaugurado restaurante <\/span><b>Xerin D\u2019Mato.<\/b><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Zayra Ayache participa de uma imers\u00e3o durante cruzeiro em alto mar<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152832\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-15.jpg\" alt=\"\" width=\"1069\" height=\"672\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-15.jpg 1069w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-15-300x189.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-15-1024x644.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-15-768x483.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-15-750x471.jpg 750w\" sizes=\"(max-width: 1069px) 100vw, 1069px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">De 9 a 12 de abril, o Movimento Mulheres Multiplicadoras vivenciou um momento hist\u00f3rico, durante o cruzeiro MCS Seaview, para imers\u00e3o, conex\u00e3o e crescimento. A empres\u00e1ria acreana Zayra Ayache foi uma das 13 mulheres que a bordo protagonizaram o primeiro de muitos encontros nacionais.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Hel\u00f4 Biasoli vem de Portugal para o 2\u00ba anivers\u00e1rio do Yoga Center<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152833\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-16.jpeg\" alt=\"\" width=\"1088\" height=\"858\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-16.jpeg 1088w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-16-300x237.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-16-1024x808.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-16-768x606.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-16-750x591.jpeg 750w\" sizes=\"(max-width: 1088px) 100vw, 1088px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A querida professora de yoga <\/span><b>Hel\u00f4 Biasoli<\/b><span style=\"font-weight: 400;\"> est\u00e1 em terras acreanas novamente. Veio dessa vez para a comemora\u00e7\u00e3o de segundo anivers\u00e1rio de inaugura\u00e7\u00e3o do Yoga Center, ocorrido no dia 5 de abril, e para rever familiares e amigos. Ela ficar\u00e1 por um m\u00eas em Rio Branco e retornar\u00e1 \u00e0 Portugal, onde reside, no dia 2 de abril. Na foto, ela com a equipe do Yoga Center: <\/span><b>Alan Dantas, Carlos Alves, Daniela Lopes, Alyx Dantas<\/b><span style=\"font-weight: 400;\"> e<\/span><b> Daniel Andrade<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<h2 style=\"text-align: left;\">\n<p><b>Cinema com sotaque do Norte e alma feminina<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152834\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-17.jpeg\" alt=\"\" width=\"1030\" height=\"908\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-17.jpeg 1030w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-17-300x264.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-17-1024x903.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-17-768x677.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-17-750x661.jpeg 750w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Rio Branco respirou arte, cinema e protagonismo feminino, com a realiza\u00e7\u00e3o da <\/span><b>I Mostra Norte Delas de Cinema<\/b><span style=\"font-weight: 400;\"> \u2014 um evento gratuito que ocupou o Cine Teatro Recreio, entre os dias 1\u00ba e 5 de abril. Com curadoria de <\/span><b>Rose Farias<\/b><span style=\"font-weight: 400;\"> e <\/span><b>Lorena Ortiz<\/b><span style=\"font-weight: 400;\">, a Mostra apresentou 24 filmes dirigidos por mulheres dos sete estados da regi\u00e3o Norte, em uma celebra\u00e7\u00e3o potente da diversidade, da cultura e das narrativas amaz\u00f4nidas.<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Idealizada pela Palm\u00e1cea Filmes e Seiva Colab Amaz\u00f4nica, e com produ\u00e7\u00e3o assinada por <\/span><b>Rose Farias, Juliana Barros, Cec\u00edlia Monteiro <\/b><span style=\"font-weight: 400;\">e <\/span><b>Isa Amsterdam<\/b><span style=\"font-weight: 400;\">, a Mostra foi mais que exibi\u00e7\u00e3o: ofereceu workshops, rodas de conversa e o II Di\u00e1logos de Mercado \u2014 transmitido ao vivo pelo YouTube \u2014 tudo com o prop\u00f3sito de valorizar o audiovisual feminino e fomentar discuss\u00f5es sobre g\u00eanero no cinema. Foi uma daquelas experi\u00eancias em que a arte se encontra com o ativismo, o talento com a tradi\u00e7\u00e3o, e o cinema com a for\u00e7a das mulheres do Norte. Um evento que j\u00e1 nasce marcante \u2014 e necess\u00e1rio.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Lan\u00e7amento com alma amaz\u00f4nica no Theatro H\u00e9lio Melo<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152835\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-18.jpeg\" alt=\"\" width=\"1053\" height=\"737\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-18.jpeg 1053w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-18-300x210.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-18-1024x717.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-18-768x538.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-18-750x525.jpeg 750w\" sizes=\"(max-width: 1053px) 100vw, 1053px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Na noite do dia 28 de mar\u00e7o, o Theatro H\u00e9lio Melo foi palco de emo\u00e7\u00e3o e celebra\u00e7\u00e3o com o lan\u00e7amento do livro <\/span><i><span style=\"font-weight: 400;\">&#8220;Varadouro: a Hist\u00f3ria de Maria, Mulher Seringueira&#8221;<\/span><\/i><span style=\"font-weight: 400;\">, do escritor <\/span><b>Edson Lodi<\/b><span style=\"font-weight: 400;\">. A obra narra a trajet\u00f3ria de for\u00e7a e resist\u00eancia de <\/span><b>Maria Gomes<\/b><span style=\"font-weight: 400;\">, mulher seringueira nascida em Pauini (AM), filha de nordestinos e a primog\u00eanita de 16 irm\u00e3os.<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O evento teve uma programa\u00e7\u00e3o cultural vibrante, com m\u00fasica ao vivo por Jamys Lima, performance teatral com Thales Vasconcelos e Deusa Maria, al\u00e9m da participa\u00e7\u00e3o especial do Coral de Estudantes da UFAC regido pelo maestro Domingos Bueno. A noite terminou com sess\u00e3o de aut\u00f3grafos \u2014 e muitos aplausos para o autor e a protagonista dessa linda hist\u00f3ria. As fotos s\u00e3o de Marcelo Dagnoni.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152836\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-19.jpeg\" alt=\"\" width=\"1087\" height=\"695\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-19.jpeg 1087w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-19-300x192.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-19-1024x655.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-19-768x491.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-19-750x480.jpeg 750w\" sizes=\"(max-width: 1087px) 100vw, 1087px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O bate-papo na cerim\u00f4nia de lan\u00e7amento do livro foi mediado por Jean Freire, articulador da C\u00e2mara Tem\u00e1tica de Cultura Ayahuasqueira<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152837\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-20.jpeg\" alt=\"\" width=\"1016\" height=\"720\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-20.jpeg 1016w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-20-300x213.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-20-768x544.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-20-120x86.jpeg 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-20-750x531.jpeg 750w\" sizes=\"(max-width: 1016px) 100vw, 1016px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Maria Gomes com o jornalista Toinho Alves, o advogado M\u00e1rcio Dagnoni e o soci\u00f3logo Bauer Gama<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152838\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-21.jpeg\" alt=\"\" width=\"950\" height=\"619\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-21.jpeg 950w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-21-300x195.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-21-768x500.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-21-750x489.jpeg 750w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Maria Gomes com Edson Lodi e sua esposa Helena<\/span><\/p>\n<p style=\"text-align: center;\">\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-152839\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22.jpeg\" alt=\"\" width=\"1008\" height=\"717\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22.jpeg 1008w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22-300x213.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22-768x546.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22-120x86.jpeg 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22-350x250.jpeg 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-22-750x533.jpeg 750w\" sizes=\"(max-width: 1008px) 100vw, 1008px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O casal Raquel e Antonio Gomes, com a filha Mariana e as amigas Andr\u00e9a Nobre e Jackie Pinheiro, respons\u00e1veis pela produ\u00e7\u00e3o e decora\u00e7\u00e3o do evento<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152840\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-23.jpeg\" alt=\"\" width=\"980\" height=\"630\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-23.jpeg 980w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-23-300x193.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-23-768x494.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-23-750x482.jpeg 750w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O casal M\u00e1rcio e Socorro Dagnoni com a homenageada<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152841\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24.jpeg\" alt=\"\" width=\"1400\" height=\"920\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24.jpeg 1400w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24-300x197.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24-1024x673.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24-768x505.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24-750x493.jpeg 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-24-1140x749.jpeg 1140w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O casal de procuradores do Estado, Leandro e Maria Jos\u00e9 Postigo, prestigiou o evento<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152842\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-25.jpeg\" alt=\"\" width=\"1008\" height=\"673\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-25.jpeg 1008w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-25-300x200.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-25-768x513.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-25-750x501.jpeg 750w\" sizes=\"(max-width: 1008px) 100vw, 1008px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Maria Gomes com seus filhos, netos, o casal Edson Lodi e Helena, e a pequena Isabel Rosa<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Mem\u00f3rias de R\u00e1dio estreou com casa cheia e boa repercuss\u00e3o<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152843\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-26.jpeg\" alt=\"\" width=\"1079\" height=\"721\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-26.jpeg 1079w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-26-300x200.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-26-1024x684.jpeg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-26-768x513.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-26-750x501.jpeg 750w\" sizes=\"(max-width: 1079px) 100vw, 1079px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A temporada de estreia da pe\u00e7a teatral <\/span><b>Mem\u00f3rias de R\u00e1dio<\/b><span style=\"font-weight: 400;\"> chegou ao fim, com casa cheia todos os dias, no Teatro de Arena do Sesc. No dia 3 foram realizadas duas apresenta\u00e7\u00f5es para escolas p\u00fablicas do Estado e, nos dias 4 e 5 de abril, as apresenta\u00e7\u00f5es foram abertas ao p\u00fablico e gratuitas. Para quem n\u00e3o conseguiu comparecer, uma boa not\u00edcia. Em breve, o <\/span><b>Grupo Beco<\/b><span style=\"font-weight: 400;\"> anunciar\u00e1 as novas temporadas, circula\u00e7\u00f5es, laborat\u00f3rios e diversos outros desdobramentos. J\u00e1 estamos aguardando!<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Arte e celebra\u00e7\u00e3o no Memorial dos Autonomistas<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152844\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27.jpg\" alt=\"\" width=\"1044\" height=\"744\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27.jpg 1044w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27-300x214.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27-1024x730.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27-768x547.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27-120x86.jpg 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27-350x250.jpg 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-27-750x534.jpg 750w\" sizes=\"(max-width: 1044px) 100vw, 1044px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Na noite do dia 15 de mar\u00e7o, o Memorial dos Autonomistas foi tomado por cores, sons e poesia durante o sarau de encerramento do <\/span><b>Curso de Marketing Digital para Produ\u00e7\u00e3o Cultural<\/b><span style=\"font-weight: 400;\">. O evento gratuito, comandado pelo multiartista<\/span><b> Diogo Soares<\/b><span style=\"font-weight: 400;\"> e convidados, celebrou o fim da jornada de aulas e palestras realizada de 10 a 14 de mar\u00e7o, na Filmoteca da Biblioteca P\u00fablica.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><b>*<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Com a presen\u00e7a do presidente da Funda\u00e7\u00e3o de Cultura Elias Mansour, <\/span><b>Minoru Kinpara<\/b><span style=\"font-weight: 400;\">, o sarau encantou o p\u00fablico com apresenta\u00e7\u00f5es musicais de <\/span><b>Maya Dourado<\/b><span style=\"font-weight: 400;\">, <\/span><b>Allan Du Acre<\/b><span style=\"font-weight: 400;\"> e <\/span><b>Carlinhos Hofre<\/b><span style=\"font-weight: 400;\"> (vocalista da banda Excomungado), al\u00e9m da dan\u00e7a de <\/span><b>J\u00falia Arantes<\/b><span style=\"font-weight: 400;\">, poesia de <\/span><b>Artur Silva<\/b><span style=\"font-weight: 400;\"> e express\u00f5es art\u00edsticas diversas, como pinturas corporais ind\u00edgenas. Os formandos receberam seus certificados em meio a aplausos e muita energia criativa. A iniciativa \u00e9 da Jackie Pinheiro Produ\u00e7\u00f5es, com financiamento da Lei Paulo Gustavo (LPG), por meio do Governo Federal e do Governo do Estado do Acre, via FEM, e apoio das empresas Caf\u00e9 Contri e Miragina. Na foto acima, estou com o casal <\/span><b>Minoru<\/b><span style=\"font-weight: 400;\"> e <\/span><b>Degmar Kinpara<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152845\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-28.jpg\" alt=\"\" width=\"1003\" height=\"752\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-28.jpg 1003w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-28-300x225.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-28-768x576.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-28-750x562.jpg 750w\" sizes=\"(max-width: 1003px) 100vw, 1003px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O artista Allan Du Acre recebendo seu certificado das m\u00e3os do Presidente da FEM e da instrutora Rayssa Alves<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152846\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-29.jpg\" alt=\"\" width=\"988\" height=\"752\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-29.jpg 988w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-29-300x228.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-29-768x585.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-29-750x571.jpg 750w\" sizes=\"(max-width: 988px) 100vw, 988px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O palestrante Mois\u00e9s Alencastro entregou o certificado \u00e0 ind\u00edgena Aline Shanenawa<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152847\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-30.jpg\" alt=\"\" width=\"1027\" height=\"664\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-30.jpg 1027w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-30-300x194.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-30-1024x662.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-30-768x497.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-30-750x485.jpg 750w\" sizes=\"(max-width: 1027px) 100vw, 1027px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O jornalista e cineasta M\u00e1rcio Levy recebendo o seu certificado<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152848\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-31.jpg\" alt=\"\" width=\"1011\" height=\"647\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-31.jpg 1011w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-31-300x192.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-31-768x491.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-31-750x480.jpg 750w\" sizes=\"(max-width: 1011px) 100vw, 1011px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Foi uma alegria ter o influenciador digital e guia de turismo T\u00e1ssio F\u00faria entre os participantes do curso<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152849\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32.jpg\" alt=\"\" width=\"1032\" height=\"740\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32.jpg 1032w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32-300x215.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32-1024x734.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32-768x551.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32-120x86.jpg 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32-350x250.jpg 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-32-750x538.jpg 750w\" sizes=\"(max-width: 1032px) 100vw, 1032px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A instrutora Xi\u00fa Shanenawa com os artistas Yawatume Yawanawa, Iskupan\u00e3 Yawanawa e Isabelle Yawanawa<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152850\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-33.jpg\" alt=\"\" width=\"1000\" height=\"738\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-33.jpg 1000w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-33-300x221.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-33-768x567.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-33-750x554.jpg 750w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Indigenas da etnia Huni Kuin encerraram a programa\u00e7\u00e3o musical:<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152851\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-34.jpg\" alt=\"\" width=\"919\" height=\"527\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-34.jpg 919w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-34-300x172.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-34-768x440.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-34-750x430.jpg 750w\" sizes=\"(max-width: 919px) 100vw, 919px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Os m\u00fasicos Diogo Soares (E), Maya Dourado (C) e Carlinhos Hofre (D) encantaram os presentes<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152852\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-35.jpg\" alt=\"\" width=\"999\" height=\"704\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-35.jpg 999w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-35-300x211.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-35-768x541.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-35-120x86.jpg 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-35-750x529.jpg 750w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O talento da dan\u00e7arina J\u00falia Arantes, em seu n\u00famero de dan\u00e7a do ventre (\u00e0 esquerda), e Artur Silva com uma pequena mostra da pot\u00eancia do slam<\/span><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152853\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-36.jpg\" alt=\"\" width=\"1005\" height=\"660\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-36.jpg 1005w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-36-300x197.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-36-768x504.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-36-750x493.jpg 750w\" sizes=\"(max-width: 1005px) 100vw, 1005px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A ilustradoras Larah Johana e Lu\u00edza Pinheiro e o fot\u00f3grafo Marcelo Dagnoni assinaram o material art\u00edstico da exposi\u00e7\u00e3o<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Agatha Moreira e o Botic\u00e1rio convidam ao ritual de autocuidado com nova linha NSPA Uva Merlot<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152854\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37.jpg\" alt=\"\" width=\"1103\" height=\"792\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37.jpg 1103w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37-300x215.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37-1024x735.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37-768x551.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37-120x86.jpg 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37-350x250.jpg 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-37-750x539.jpg 750w\" sizes=\"(max-width: 1103px) 100vw, 1103px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A Nativa SPA, do Botic\u00e1rio, acaba de lan\u00e7ar a deliciosa linha <\/span><b>NSPA Uva Merlot<\/b><span style=\"font-weight: 400;\">, um convite irresist\u00edvel para as mulheres desacelerarem e transformarem seus momentos a s\u00f3s em puro bem-estar. A campanha &#8220;Desacelere os sinais do tempo com o poder revitalizante de Nativa SPA Uva Merlot&#8221; chega com a linda <\/span><b>Agatha Moreira<\/b><span style=\"font-weight: 400;\"> como garota-propaganda, inspirando a priorizar o autocuidado. Pelas redes sociais, a atriz compartilha como encontrar tempo para si pode ser um luxo necess\u00e1rio. Fica a dica para um ritual de beleza que nutre o corpo e a alma.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>O poder da linha Nativa SPA Uva Merlot para rituais de autocuidado<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152855\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-38.jpeg\" alt=\"\" width=\"1001\" height=\"658\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-38.jpeg 1001w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-38-300x197.jpeg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-38-768x505.jpeg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-38-750x493.jpeg 750w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A linha <\/span><b>Nativa SPA Uva Merlot<\/b><span style=\"font-weight: 400;\"> chega para ampliar o portf\u00f3lio da marca com produtos de cuidados, com fragr\u00e2ncia \u00fanica desenvolvida a partir da neuroci\u00eancia, que tem o exclusivo acorde olfativo <\/span><b>Merlot Essence<\/b><span style=\"font-weight: 400;\">, que comprovadamente promove mais confian\u00e7a. O lan\u00e7amento une a perfuma\u00e7\u00e3o exuberante dos vinhedos e da madeira a sucul\u00eancia da fruta com a potente a\u00e7\u00e3o de desacelerar os sinais do tempo na pele desde o primeiro uso. A novidade conta com seis itens: Lo\u00e7\u00e3o Nutritiva Desodorante, Creme Esfoliante Corporal, Sabonete L\u00edquido, \u00d3leo Bif\u00e1sico Hidratante Desodorante Corporal e Body Splash Desodorante Col\u00f4nia trazendo a explos\u00e3o de eleg\u00e2ncia que carrega a sucul\u00eancia da uva com a sofistica\u00e7\u00e3o das madeiras.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Collab de peso do Botic\u00e1rio com NBA, Fred Bruno e Raulzinho<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152856\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-39.jpg\" alt=\"\" width=\"775\" height=\"517\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-39.jpg 775w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-39-300x200.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-39-768x512.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-39-750x500.jpg 750w\" sizes=\"(max-width: 775px) 100vw, 775px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Para apresentar a collab in\u00e9dita de\u00a0<\/span><b>MEN &amp; NBA<\/b><span style=\"font-weight: 400;\">, que une performance e autocuidado para os homens, o\u00a0<\/span><b>Botic\u00e1rio<\/b><span style=\"font-weight: 400;\">\u00a0lan\u00e7a a campanha\u00a0<\/span><b>\u201cO Faro da NBA\u201d<\/b><span style=\"font-weight: 400;\">\u00a0protagonizada por Raulzinho, lenda brasileira que atuou na NBA e um dos principais jogadores de basquete do Brasil, e Fred Bruno, apresentador e criador de conte\u00fado reconhecido no universo esportivo brasileiro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">A dupla vai usar o &#8220;faro&#8221; apurado para encontrar talentos durante um jogo exclusivo. A linha, com tecnologia Power Fresh e notas amadeiradas, promete performance e bem-estar para o dia a dia. A cole\u00e7\u00e3o inclui desodorante col\u00f4nia, desodorante antitranspirante, shower gel, sabonete em barra e necessaire, oferecendo praticidade e alta performance para quem busca bem-estar no dia a dia.<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>O Botic\u00e1rio expande portf\u00f3lio com L\u2019eau de Lily lanche<\/b><b><br \/>\n<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152857\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-40.jpg\" alt=\"\" width=\"715\" height=\"990\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-40.jpg 715w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-40-217x300.jpg 217w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Na vanguarda da inova\u00e7\u00e3o e do desenvolvimento de produtos que conectam lovers da marca, o <\/span><b>Botic\u00e1rio<\/b><span style=\"font-weight: 400;\"> apresenta lan\u00e7amento de perfumaria feminina com <\/span><b>L\u2019eau de Lily Blanche<\/b><span style=\"font-weight: 400;\">. A novidade, que j\u00e1 est\u00e1 \u00e0 venda em todo o Brasil e canais de vendas oficiais da marca mais amada pelos brasileiros, apresenta a personalidade presente no DNA do buqu\u00ea floral branco de Lily, em um contraste de frescor com cremosidade marcante e roupagem olfativa ideal para o dia.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com alta fixa\u00e7\u00e3o, o floral combina o brilho dos c\u00edtricos, como a mandarina, somada \u00e0s notas frescas orvalhadas das flores transparentes, como a fr\u00e9sia. Esse frescor \u00e9 contrastado com o floral branco do Jasmim Air colhido ao amanhecer, quando est\u00e1 com orvalho sob suas p\u00e9talas, exalando floralidade, acrescentando ao fundo a cremosidade do white musk com nuances ambaradas e refor\u00e7ando a sofistica\u00e7\u00e3o das notas amadeiradas de cedro e musgo cristal.\u00a0<\/span><\/p>\n<p style=\"text-align: left;\">\n<h2><b>Mundo Bita embala nova campanha de Boti Baby, do Botic\u00e1rio<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152858\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41.jpg\" alt=\"\" width=\"1003\" height=\"605\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41.jpg 1003w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41-300x181.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41-768x463.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41-750x452.jpg 750w\" sizes=\"(max-width: 1003px) 100vw, 1003px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Entre tantos momentos que refor\u00e7am a conex\u00e3o entre tutores e os pequenos, o banho \u00e9 um dos mais especiais, pois \u00e9 quando o momento de higiene e carinho se encontram para o cuidado do beb\u00ea. Pensando nisso, <\/span><b>Boti Baby<\/b><span style=\"font-weight: 400;\">, marca voltada para o cuidado infantil do <\/span><b>Botic\u00e1rio<\/b><span style=\"font-weight: 400;\">, se une ao<\/span><b> Mundo Bita<\/b><span style=\"font-weight: 400;\"> para transformar essa rotina em uma experi\u00eancia ainda mais l\u00fadica e envolvente. Com base no conceito da campanha, \u201cO Amor d\u00e1 um Banho\u201d \u00e9 a nova m\u00fasica, criada especialmente para embalar o momento do banho, estimulando os sentidos e fortalecendo os la\u00e7os afetivos.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A marca se baseia no fato de que o olfato \u00e9 um dos primeiros sentidos desenvolvidos no beb\u00ea e tem o poder de evocar mem\u00f3rias e despertar emo\u00e7\u00f5es, al\u00e9m de possuir um papel significativo na forma como o mundo ao redor \u00e9 percebido para desenvolver a campanha. Por isso, a fragr\u00e2ncia dessa linha \u00e9 desenvolvida por meio de neuroci\u00eancia com ingredientes que despertam sensa\u00e7\u00f5es de felicidade. E, como o momento do banho \u00e9 quando os respons\u00e1veis refor\u00e7am essa conex\u00e3o com cantigas de banho, risadas e toque, a trilha sonora, com a assinatura do Mundo Bita, torna esse momento ainda mais especial associado ao uso dos produtos de Boti Baby.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152858\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41.jpg\" alt=\"\" width=\"1003\" height=\"605\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41.jpg 1003w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41-300x181.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41-768x463.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-41-750x452.jpg 750w\" sizes=\"(max-width: 1003px) 100vw, 1003px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O v\u00eddeo de campanha <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=FeGeNPBLpEU\"><b>\u201cO Amor d\u00e1 um Banho\u201d<\/b><\/a><span style=\"font-weight: 400;\">, criada pela AlmapBBDO, com a m\u00fasica j\u00e1 est\u00e1 dispon\u00edvel no <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=FeGeNPBLpEU\"><span style=\"font-weight: 400;\">YouTube<\/span><\/a><span style=\"font-weight: 400;\"> e nos canais oficiais do Botic\u00e1rio e Mundo Bita.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Gabriel Medina \u00e9 o embaixador da nova linha Clash, do Botic\u00e1rio<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-152860\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-43.jpg\" alt=\"\" width=\"1037\" height=\"600\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-43.jpg 1037w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-43-300x174.jpg 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-43-1024x592.jpg 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-43-768x444.jpg 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-43-750x434.jpg 750w\" sizes=\"(max-width: 1037px) 100vw, 1037px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Gabriel Medina \u00e9 o embaixador de <\/span><b>Clash,<\/b><span style=\"font-weight: 400;\"> nova fragr\u00e2ncia masculina do<\/span><b> Botic\u00e1rio<\/b><span style=\"font-weight: 400;\">, marca de beleza mais amada e preferida dos brasileiros, que desafia os padr\u00f5es cl\u00e1ssicos de sucesso masculino e instiga o homem a enfrentar a press\u00e3o para emergir mais forte diante dos desafios. Com a premissa \u201cda press\u00e3o nasce a for\u00e7a\u201d, a marca se conecta com aqueles que encaram os obst\u00e1culos de frente, com coragem e determina\u00e7\u00e3o, e celebra o homem que n\u00e3o teme o desconforto em busca da sua melhor vers\u00e3o. Gabriel Medina, um atleta de alta performance que transcende o esporte, personifica essa busca incans\u00e1vel por superar desafios. Sua jornada, marcada por batalhas tanto no surf quanto na vida pessoal, inspira a marca a enaltecer a for\u00e7a e a resili\u00eancia que surgem da supera\u00e7\u00e3o.<\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 13.2px;\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt; line-height: normal; text-align: center;\"><strong style=\"color: #000000; font-size: 16px; text-align: center;\"><span style=\"font-family: Verdana, sans-serif;\"><img decoding=\"async\" class=\" size-full wp-image-66615\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2020\/04\/gazeta_estilo_patrocinios.jpg\" alt=\"gazeta estilo patrocinios\" width=\"698\" height=\"160\" \/>\u00a0<\/span><\/strong><\/p>\n<p><strong style=\"font-size: 16px; text-align: center;\">\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Simone recebe o acreano durante almo\u00e7o no Fasano, em S\u00e3o Paulo O jornalista acreano Nostradamus Fran\u00e7a, que hoje reside em S\u00e3o Paulo, tem uma hist\u00f3ria interessante que o liga \u00e0 cantora Simone Bittencourt de Oliveira, a Simone. Ele nasceu no dia 25 de dezembro e o hit da cantora \u201cEnt\u00e3o \u00e9 Natal\u201d embalou muitas de [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":152822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"custom","single_blog_custom":"110746","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"1","show_inline_post_related":"0","post_calculate_word_method":"str_word_count"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0","format":"standard","jnews_video_option_group":[[]],"subtitle":""},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_review":[],"enable_review":"0","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[{"good_text":""}],"bad":[{"bad_text":""}],"score_override":"0","override_value":"","rating":[{"rating_text":"","rating_number":"10"}],"price":[{"shop":"","price":"","link":"","icon":""}],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-152816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jackie-pinheiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLUNA JACKIE \u2013 13\/04\/2025 - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLUNA JACKIE \u2013 13\/04\/2025 - Agazeta.net\" \/>\n<meta property=\"og:description\" content=\"Simone recebe o acreano durante almo\u00e7o no Fasano, em S\u00e3o Paulo O jornalista acreano Nostradamus Fran\u00e7a, que hoje reside em S\u00e3o Paulo, tem uma hist\u00f3ria interessante que o liga \u00e0 cantora Simone Bittencourt de Oliveira, a Simone. Ele nasceu no dia 25 de dezembro e o hit da cantora \u201cEnt\u00e3o \u00e9 Natal\u201d embalou muitas de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T22:36:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1191\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jackie Prinheiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jackie Prinheiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/\",\"name\":\"COLUNA JACKIE \u2013 13\/04\/2025 - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg\",\"datePublished\":\"2025-04-14T22:36:26+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg\",\"width\":1191,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COLUNA JACKIE \u2013 13\/04\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\",\"name\":\"Jackie Prinheiro\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLUNA JACKIE \u2013 13\/04\/2025 - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/","og_locale":"pt_BR","og_type":"article","og_title":"COLUNA JACKIE \u2013 13\/04\/2025 - Agazeta.net","og_description":"Simone recebe o acreano durante almo\u00e7o no Fasano, em S\u00e3o Paulo O jornalista acreano Nostradamus Fran\u00e7a, que hoje reside em S\u00e3o Paulo, tem uma hist\u00f3ria interessante que o liga \u00e0 cantora Simone Bittencourt de Oliveira, a Simone. Ele nasceu no dia 25 de dezembro e o hit da cantora \u201cEnt\u00e3o \u00e9 Natal\u201d embalou muitas de [&hellip;]","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/","og_site_name":"Agazeta.net","article_published_time":"2025-04-14T22:36:26+00:00","og_image":[{"width":1191,"height":788,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg","type":"image\/jpeg"}],"author":"Jackie Prinheiro","twitter_card":"summary_large_image","twitter_image":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg","twitter_misc":{"Escrito por":"Jackie Prinheiro","Est. tempo de leitura":"26 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/","name":"COLUNA JACKIE \u2013 13\/04\/2025 - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg","datePublished":"2025-04-14T22:36:26+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2025\/04\/Foto-5.jpeg","width":1191,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-13-04-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"COLUNA JACKIE \u2013 13\/04\/2025"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c","name":"Jackie Prinheiro","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/152816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=152816"}],"version-history":[{"count":0,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/152816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/152822"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=152816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=152816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=152816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}