{"id":141689,"date":"2024-10-09T21:58:15","date_gmt":"2024-10-09T21:58:15","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=141689"},"modified":"2024-10-17T07:28:09","modified_gmt":"2024-10-17T12:28:09","slug":"coluna-jackie-09-10-2024","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/","title":{"rendered":"COLUNA JACKIE \u2013 09\/10\/2024"},"content":{"rendered":"<h2><b>Donatinho, filho de Jo\u00e3o Donato, est\u00e1 no Acre gravando novo videoclipe<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">No dia 7 de outubro, influenciadores, jornalistas e artistas participaram no Flutuante Malveira da grava\u00e7\u00e3o do videoclipe do single &#8220;Intuir&#8221;, feat do talentoso m\u00fasico Donatinho com seu pai Jo\u00e3o Donato. Com letras de Tulipa Ruiz e Gustavo Ruiz, essa m\u00fasica traz uma mensagem de esperan\u00e7a p\u00f3s COVID-19 e para os povos da Amaz\u00f4nia, que sofrem com as devastadoras queimadas. A m\u00fasica faz parte do \u00e1lbum Sintetiza2, que foi gravado durante a pandemia, sendo o \u00faltimo trabalho do renomado artista Jo\u00e3o Donato, um dos grandes nomes da m\u00fasica brasileira, que faleceu no ano passado. Donatinho veio com a equipe do selo musical Sound Department, que tem a parceria local da artista e produtora de cinema Karla Martins. Uma bela homenagem ao seu pai!<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">**<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O trabalho \u00e9 uma continua\u00e7\u00e3o do \u00e1lbum Sintetizamor, que ganhou o pr\u00eamio de melhor \u00e1lbum de M\u00fasica Eletr\u00f4nica, pela Rolling Stone Brasil, em 2017. J\u00e1 estamos ansiosos aguardando o lan\u00e7amento do single, que estar\u00e1 no dia 24 de outubro em todas as plataformas digitais. S\u00f3 posso revelar uma coisinha: a m\u00fasica \u00e9 lindaaa!\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141694\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Design-sem-nome.jpg\" alt=\"\" width=\"1143\" height=\"1160\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Donatinho, filho do imortal Jo\u00e3o Donato, desembarcou no Acre com a equipe do selo musical Sound Department para as grava\u00e7\u00f5es do videoclipe Intuir. Na foto, comigo e Mois\u00e9s Alencastro nos bastidores da grava\u00e7\u00e3o<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141695\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-2-1.jpg\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Artistas, jornalistas e influenciadores fizeram parte da figura\u00e7\u00e3o. Da esquerda para a direita, a artista Duda Mendon\u00e7a, as jornalistas Alex Machado e Abigail Sunamita, eu e Aleksandra Shogenova, a @russa_no_acre<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141696\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-3-1.jpg\" alt=\"\" width=\"1321\" height=\"1564\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">\u00c9 sempre muito divertido encontrar a russa Aleksandra Shogenova\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141697\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-4.jpg\" alt=\"\" width=\"1209\" height=\"995\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A maquiadora Allana di Souza deu o nome na prepara\u00e7\u00e3o do artista e figurantes. Talentosa e muito querida!<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141698\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-5.jpg\" alt=\"\" width=\"1150\" height=\"1477\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A rep\u00f3rter e apresentadora Aline Rocha esteve no local gravando os bastidores. Mostrar\u00e1 tudo no programa Almanacre, nesse s\u00e1bado, \u00e0s 13h45, na Rede Amaz\u00f4nica<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141699\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-6.jpg\" alt=\"\" width=\"1280\" height=\"720\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Equipe de produ\u00e7\u00e3o do videoclipe<\/span><\/p>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Artista pl\u00e1stico acreano Fernando Fran\u00e7a exp\u00f5e no Museu do Amanh\u00e3 e \u00e9 prestigiado pela Ministra Marina Silva e Jo\u00e3o C\u00e2ndido Portinari<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O artista pl\u00e1stico acreano <\/span><b>Fernando Fran\u00e7a<\/b><span style=\"font-weight: 400;\"> est\u00e1 com sua exposi\u00e7\u00e3o \u2018Encantes\u2019, no Museu do Amanh\u00e3, Rio de Janeiro-RJ, desde o dia 4 de outubro. A exposi\u00e7\u00e3o abriu o G20, com a presen\u00e7a de diversas autoridades como a ministra <\/span><b>Marina Silva<\/b><span style=\"font-weight: 400;\">, que estavam no local para participarem da abertura da reuni\u00e3o ministerial do GT de Sustentabilidade Ambiental e Clim\u00e1tica do G20, no museu, no dia 3. O filho do grande artista C\u00e2ndido Portinari, <\/span><b>Jo\u00e3o C\u00e2ndido Portinari<\/b><span style=\"font-weight: 400;\">, tamb\u00e9m conheceu as obras. A exposi\u00e7\u00e3o fica aberta para visita\u00e7\u00e3o p\u00fablica durante um m\u00eas.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141700\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-7.jpg\" alt=\"\" width=\"1479\" height=\"1030\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O artista acreano com a sua amiga Marina Silva, ministra do Meio Ambiente e Mudan\u00e7a do Clima, o secret\u00e1rio-executivo do MMA, Jo\u00e3o Paulo Capobianco, e a secret\u00e1ria da Mudan\u00e7a do Clima, Ana Toni<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141701\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-8.jpg\" alt=\"\" width=\"1349\" height=\"1304\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Fran\u00e7a com Jo\u00e3o C\u00e2ndido Portinari, filho do grande artista Portinari<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141702\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-9.jpg\" alt=\"\" width=\"1628\" height=\"1216\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O artista com Kalu Chaves, Jo\u00e3o Torres, Christine Ruta e Jo\u00e3o C\u00e2ndido Portinari<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141703\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-10.jpg\" alt=\"\" width=\"956\" height=\"1342\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Fernando Fran\u00e7a e sua esposa Kalu Chaves<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Caciques ind\u00edgenas Laura e Tashka Yawanawa participam da Semana do Clima de Nova Iorque<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O casal <\/span><b>Laura<\/b><span style=\"font-weight: 400;\"> e <\/span><b>Tashka Yawanawa<\/b><span style=\"font-weight: 400;\"> participou do evento Exploring the Amazon Contribution on Flight in Climate Change, organizado pela Conserva\u00e7\u00e3o Internacional, na Semana do Clima de Nova Iorque, em Nova Iorque-EUA, de 22 a 29 de setembro. Eles foram palestrantes nesse evento que reuniu l\u00edderes mundiais de diversos setores, com representantes de empresas, academia, governos e sociedade civil, totalizando mais de 600 eventos e atividades paralelas na cidade de Nova Iorque, nos Estados Unidos. A cada ano, estes l\u00edderes e tomadores de decis\u00e3o de diversas partes do mundo se encontram para discutir prioridades para a a\u00e7\u00e3o clim\u00e1tica. No dia 25 de setembro, o casal participou de um jantar organizado pelo estilista <\/span><b>Francisco Costa<\/b><span style=\"font-weight: 400;\">, diretor criativo da cole\u00e7\u00e3o feminina da Calvin Klein e da marca Costa Brazil, com parceiros, apoiadores e convidados engajados na causa ind\u00edgena, ambiental e social<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141704\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-11.jpg\" alt=\"\" width=\"1170\" height=\"806\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Caciques Laura e Tashka Yawanawa proferiram palestra na Semana do Clima de Nova Iorque<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141705\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-12.jpg\" alt=\"\" width=\"1170\" height=\"1204\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Laura e Tashka com o diretor criativo da Calvin Klein woman, Francisco Costa, e Maur\u00edcio Bianco, em jantar organizado pelo estilista<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141706\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-13.jpg\" alt=\"\" width=\"1170\" height=\"1114\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O casal participou tamb\u00e9m de uma reuni\u00e3o com executivos da famosa marca AVEDA Corporation Inc.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Mapu Huni Kuin se apresentou com Alok no Festival Global Citizen 2024<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O <\/span><b>DJ Alok<\/b><span style=\"font-weight: 400;\"> tamb\u00e9m participou da Semana do Clima de Nova Iorque e convidou m\u00fasicos e personalidades de diversas etnias ind\u00edgenas para participarem da apresenta\u00e7\u00e3o do \u00e1lbum O Futuro \u00e9 Ancestral. Entre os convidados estavam o acreano Mapu Huni Kuin e a deputada federal C\u00e9lia Xakriaba. A apresenta\u00e7\u00e3o ocorreu no dia 28 de setembro, no <\/span><b>Festival Global Citizen 2024<\/b><span style=\"font-weight: 400;\">.\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141707\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-14.jpg\" alt=\"\" width=\"1045\" height=\"899\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Maku Huni Kuin com Alok, o produtor MarkL e Rafa Sardina<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141708\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-15.jpg\" alt=\"\" width=\"784\" height=\"1181\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A deputada federal C\u00e9lia Xakriab\u00e1 com Mapu Huni Kuin, nos bastidores<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Cinema acreano \u00e9 premiado no Brasil Cine Mundi, em BH<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O cineasta <\/span><b>S\u00e9rgio Carvalho<\/b><span style=\"font-weight: 400;\"> e a produtora <\/span><b>Karla Martins<\/b><span style=\"font-weight: 400;\">, da Saci Filmes, brilharam na 15\u00aa edi\u00e7\u00e3o do Brasil Cine Mundi &#8211; International Coproduction Meeting, realizada em Belo Horizonte. L\u00e1, o novo projeto da Saci Filmes em co-produ\u00e7\u00e3o com a Comdom\u00ednio Filmes, intitulado &#8220;Estirada&#8221;, foi premiado, conquistando a aten\u00e7\u00e3o do p\u00fablico e da cr\u00edtica.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A recompensa n\u00e3o poderia ser melhor: a oportunidade de levar &#8220;Estirada&#8221; para o prestigiado Festival de M\u00e1laga, na Espanha, em parceria com o Projeto Paradiso. Esse reconhecimento assegurou ao projeto uma vaga no laborat\u00f3rio e no mercado do renomado festival, que acontecer\u00e1 em mar\u00e7o de 2025. O Brasil Cine Mundi \u00e9 organizado pela Universo Produ\u00e7\u00e3o, que tem se destacado na promo\u00e7\u00e3o do cinema nacional e no fomento a colabora\u00e7\u00f5es internacionais. Parab\u00e9ns ao S\u00e9rgio e \u00e0 Karla pelo sucesso e pela contribui\u00e7\u00e3o ao cen\u00e1rio cultural brasileiro!<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141709\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-16.jpg\" alt=\"\" width=\"1170\" height=\"815\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Na foto, S\u00e9rgio e Karla com grandes profissionais do jornalismo cinematogr\u00e1fico brasileiro: Merten, Zanin, Maria do Ros\u00e1rio e Marcos Santu\u00e1rio<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Festival Pachamama 2024 leva filmes a munic\u00edpios do Alto Acre e em cidades da Bol\u00edvia e Peru<\/b><\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-141710\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-17.jpg\" alt=\"\" width=\"768\" height=\"1086\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Aprovado na lei de incentivo \u00e0 cultura, Lei Paulo Gustavo (LPG), do governo do Acre, por meio da Funda\u00e7\u00e3o Elias Mansour (FEM), o <\/span><b>Festival Pachamama: da Floresta aos Andes<\/b><span style=\"font-weight: 400;\">, realizado pela produtora Saci Filmes, iniciou sua primeira fase no dia 8 de novembro, levando o melhor do cinema latino-americano e amaz\u00f4nico a cinco cidades: em Xapuri, na Reserva Extrativista (Resex) Chico Mendes; Brasileia; Cobija (Bol\u00edvia); Assis Brasil; e finaliza em Puerto Maldonado, no Peru.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141711\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-18.jpg\" alt=\"\" width=\"1170\" height=\"1215\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O idealizador do Festival Pachamama, cineasta S\u00e9rgio de Carvalho<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>DJ Cau Bartholo est\u00e1 passando temporada em Trancoso<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141712\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-19.jpg\" alt=\"\" width=\"873\" height=\"1026\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A talentosa DJ <\/span><b>Cau Bartholo<\/b><span style=\"font-weight: 400;\"> est\u00e1 passando uma temporada especial em Trancoso, na Bahia, a convite do DJ e produtor <\/span><b>Tony Monteiro<\/b><span style=\"font-weight: 400;\">. A atmosfera vibrante da regi\u00e3o tem sido o cen\u00e1rio perfeito para suas apresenta\u00e7\u00f5es, que j\u00e1 est\u00e3o agitando as casas \u201cL\u00e1 no Dom\u201d e \u201cBadalado\u201d. A mistura de ritmos e a energia contagiante de Cau prometem fazer dessas noites uma experi\u00eancia inesquec\u00edvel para os amantes da m\u00fasica eletr\u00f4nica.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Sandali\u00e1ria Rio Branco ganha filial na Esta\u00e7\u00e3o Experimental<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">No dia 26 de setembro, a alegria tomou conta dos f\u00e3s da <\/span><b>Sandali\u00e1ria Rio Branco<\/b><span style=\"font-weight: 400;\"> com a inaugura\u00e7\u00e3o de uma nova filial na rua Na\u00e7\u00f5es Unidas, 2828, no bairro Esta\u00e7\u00e3o Experimental. O evento foi marcado por um clima festivo e animado, atraindo clientes e amigos da marca, que puderam conferir de perto as novidades.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A nova loja traz os lan\u00e7amentos das queridas marcas Crocs, Havaianas, Colcci, Coca-Cola, Kenner e Blessed. Al\u00e9m disso, os visitantes encontraram uma variedade de produtos, incluindo os adorados bottons da Crocs, acess\u00f3rios para sand\u00e1lias e uma ampla sele\u00e7\u00e3o de t\u00eanis masculinos e femininos. Para os pequenos, a loja tamb\u00e9m conta com diversas op\u00e7\u00f5es na linha infantil. Confira alguns registros da festa!<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141713\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-20.jpg\" alt=\"\" width=\"960\" height=\"997\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Colunistas Gigi Hanan, Roberta Lima e Mois\u00e9s Alencastro comigo<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141714\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-21.jpg\" alt=\"\" width=\"960\" height=\"1041\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Eu, M\u00e1rcia Abreu e Mois\u00e9s Alencastro fizemos as nossas compras<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141715\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-22.jpeg\" alt=\"\" width=\"960\" height=\"966\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">As queridas anfitri\u00e3s Polyanna Neto, Caroline Nascimento e Viviane Castro<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Avant-premi\u00e8re de Coringa<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">No dia 3 de outubro o Via Verde Shopping e o Cine Ara\u00fajo realizaram uma sess\u00e3o exclusiva do filme \u2018Coringa: Del\u00edrio a Dois\u2019, para a imprensa, influenciadores e convidados. Uma das boas not\u00edcias que recebemos no evento foi a inaugura\u00e7\u00e3o da tecnologia Proje\u00e7\u00e3o a laser, um equipamento mais sustent\u00e1vel que tamb\u00e9m traz mais qualidade \u00e0s imagens. Parab\u00e9ns pela iniciativa!<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141716\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-23.jpeg\" alt=\"\" width=\"808\" height=\"715\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Com os anfitri\u00f5es Daniel Ferreira e N\u00e9ia Aielo<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141717\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-24.jpeg\" alt=\"\" width=\"781\" height=\"700\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Os colunistas Giuliana Evangelista, Mois\u00e9s Alencastro, M\u00e1rcia Abreu, Cl\u00e1udia Abreu e Roberta Lima estiveram presentes na pr\u00e9-estreia<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141718\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-25.jpeg\" alt=\"\" width=\"855\" height=\"1059\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Amei reencontrar a jornalista e artista Abigail Sunamita<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>PT retorna \u00e0 C\u00e2mara com elei\u00e7\u00e3o de Andr\u00e9 Kamai\u00a0<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141719\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-26.jpeg\" alt=\"\" width=\"1281\" height=\"1279\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A boa not\u00edcia desse pleito eleitoral foi a vit\u00f3ria de <\/span><b>Andr\u00e9 Kamai<\/b><span style=\"font-weight: 400;\"> (PT), soci\u00f3logo e ex-presidente do Partido dos Trabalhadores no Acre. Ele tamb\u00e9m exerceu os cargos secret\u00e1rio de Pol\u00edticas de Juventude de Rio Branco, assessor do governador Binho Marques e secret\u00e1rio da Casa Civil de Rio Branco. A ascens\u00e3o do petista ao cargo \u00e9 um sopro de esperan\u00e7a para o campo progressista.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141720\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-27.jpeg\" alt=\"\" width=\"960\" height=\"987\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A jornalista <\/span><b>Tylara Pinheiro<\/b><span style=\"font-weight: 400;\">, que estava no Acre a trabalho e foi dar um abra\u00e7o no amigo<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Surpresa para a Lu<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141721\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-28.jpeg\" alt=\"\" width=\"720\" height=\"772\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A querida cabeleireira e maquiadora <\/span><b>Luciane Guimar\u00e3es<\/b><span style=\"font-weight: 400;\">, s\u00f3cia do Master Fio, ganhou uma festa surpresa no sal\u00e3o, s\u00e1bado, 5, em celebra\u00e7\u00e3o ao seu anivers\u00e1rio. A festa, organizada por sua grande amiga e s\u00f3cia <\/span><b>Luana Lima<\/b><span style=\"font-weight: 400;\">, contou com a presen\u00e7a de amigos e clientes que n\u00e3o perderam a oportunidade de parabenizar a Lu por mais um ano de vida.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>IFAC tem novo reitor<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141722\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-29.png\" alt=\"\" width=\"650\" height=\"460\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Foto-29.png 650w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Foto-29-300x212.png 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Foto-29-120x86.png 120w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O professor<\/span><b> F\u00e1bio Storch de Oliveira <\/b><span style=\"font-weight: 400;\">foi nomeado no dia 1\u00ba de outubro como o novo reitor do Instituto Federal do Acre (Ifac) para os pr\u00f3ximos quatro anos. O docente, que ocupava o cargo de pr\u00f3-reitor de Extens\u00e3o, foi eleito com 33% dos votos v\u00e1lidos, em setembro deste ano, durante processo eleitoral para Reitoria e Diretorias Gerais de campi.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Cia Cata-Ventos inaugura site com cursos gratuitos de arte e cultura em Rio Branco<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A Cia Cata-Ventos de Cultura lan\u00e7ou oficialmente seu site, onde j\u00e1 est\u00e3o dispon\u00edveis informa\u00e7\u00f5es sobre uma variedade de cursos e oficinas culturais gratuitas. Os interessados podem acessar o portal\u00a0<\/span><a href=\"https:\/\/ciacataventos.org\/\"><span style=\"font-weight: 400;\">https:\/\/ciacataventos.org\/<\/span><\/a><span style=\"font-weight: 400;\">\u00a0para conhecer as op\u00e7\u00f5es, que incluem teatro, dan\u00e7a, m\u00fasica, capoeira, artes circenses, empreendedorismo cultural, entre outras.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voltada para a comunidade de Rio Branco e regi\u00e3o, a Cia oferece atividades que visam o aprendizado, desenvolvimento pessoal e a promo\u00e7\u00e3o da cultura local. O objetivo \u00e9 abrir portas para que todos possam aprimorar seus talentos e se conectar com a cultura local.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Uranium Filmes abre inscri\u00e7\u00f5es para curso de dire\u00e7\u00e3o de cinema em Rio Branco<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O cineasta <\/span><b>Tiago Melo<\/b><span style=\"font-weight: 400;\"> ministra o segundo m\u00f3dulo gratuito da oficina \u201cCria\u00e7\u00e3o Audiovisual: Da Ideia ao Roteiro, do Roteiro \u00e0 Filmagem\u201d, em Rio Branco (AC). A programa\u00e7\u00e3o est\u00e1 marcada para o per\u00edodo de 14 a 18 de outubro, das 15h \u00e0s 19h, na Filmoteca Acreana &#8211; unidade anexa \u00e0 Biblioteca P\u00fablica na regi\u00e3o central da cidade. Durante cinco dias, os alunos experimentam no\u00e7\u00f5es t\u00e9cnicas de dire\u00e7\u00e3o, decupagem (<\/span><i><span style=\"font-weight: 400;\">processo de divis\u00e3o de cenas em planos de filmagem<\/span><\/i><span style=\"font-weight: 400;\">) e linguagem cinematogr\u00e1fica. Com o uso da c\u00e2mera, eles devem aprender maneiras de como transformar a narrativa do roteiro em imagem.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No m\u00f3dulo anterior, dedicado ao desenvolvimento da escrita para o cinema, cerca de 200 pessoas de diversas idades e \u00e1reas de atua\u00e7\u00e3o se inscreveram no curso. Na \u00e9poca, em 2021, Tiago Melo utilizou o formato remoto para atender a demanda e cumprir as medidas de distanciamento social adotadas no pa\u00eds em combate \u00e0 pandemia do novo coronav\u00edrus. Agora, com aulas presenciais e exerc\u00edcios pr\u00e1ticos, a disponibilidade de vagas contempla apenas 20 candidatos para o melhor aproveitamento da turma. As inscri\u00e7\u00f5es devem ser feitas por meio do preenchimento de um formul\u00e1rio online que est\u00e1 dispon\u00edvel no perfil @criacao.audiovisual, no Instagram, at\u00e9 \u00e0s 21h do dia 9 de outubro.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Alba Botafogo<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141725\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-31.jpeg\" alt=\"\" width=\"489\" height=\"807\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Tive o prazer de conhecer o encantador restaurante e casa de arte <\/span><b>Alba Botafogo<\/b><span style=\"font-weight: 400;\">, um verdadeiro ref\u00fagio cultural em um casar\u00e3o hist\u00f3rico no cora\u00e7\u00e3o de Botafogo, no Rio de Janeiro. Agrade\u00e7o a hospitalidade do empres\u00e1rio e promotor de eventos <\/span><b>L\u00e9o Mar\u00e7al<\/b><span style=\"font-weight: 400;\">, s\u00f3cio propriet\u00e1rio e figura querida e respeitada no cen\u00e1rio carioca, que tem se destacado por seu trabalho junto \u00e0 imprensa e \u00e0 classe art\u00edstica, sempre promovendo eventos que celebram a cultura local. O Alba \u00e9 com certeza um destino imperd\u00edvel para quem aprecia boa comida e arte. N\u00e3o deixem de visitar!<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Desfile da cole\u00e7\u00e3o Yawa Tari de Nedina Yawanawa marcou o m\u00eas de setembro<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Um dos acontecimentos mais marcantes de setembro foi o desfile de lan\u00e7amento da cole\u00e7\u00e3o de roupas ind\u00edgenas Yawa Tari, assinada pela designer <\/span><b>Nedina Yawanawa<\/b><span style=\"font-weight: 400;\">, diretora da Secretaria dos Povos Ind\u00edgenas. No dia 6 de setembro, ela apresentou no Espa\u00e7o Vivencie Etnoviv\u00eancias, durante a Expoacre, as 15 pe\u00e7as que criou, inspiradas nos kenes yawa, unindo tradi\u00e7\u00e3o e ancestralidade, retratando os seres sagrados da floresta amaz\u00f4nica, segundo a cosmovis\u00e3o do povo Yawanawa. Os desenhos nas roupas fazem alus\u00e3o as diversas figuras da floresta como \u00e1guas, vento, folhas do kaw\u00e1, cip\u00f3, animais sagrados, armas de guerra, entre outros s\u00edmbolos. A realiza\u00e7\u00e3o foi da Secretaria de Turismo do Acre e da Secretaria dos Povos Ind\u00edgenas. A produ\u00e7\u00e3o foi assinada por mim e Mois\u00e9s Alencastro.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141726\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-32.jpeg\" alt=\"\" width=\"1199\" height=\"671\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A estilista com os modelos que desfilaram a cole\u00e7\u00e3o Yawa Tari<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141727\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-33.jpeg\" alt=\"\" width=\"862\" height=\"969\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O reconhecimento dos presentes ao bel\u00edssimo trabalho de Nedina Yawanawa<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141728\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-34.jpeg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Ap\u00f3s o desfile, os colunistas Jackie Pinheiro, Mois\u00e9s Alencastro e M\u00e1rcia Abreu foram recebidos pelos jornalistas W\u00e2nia Pinheiro e Douglas Richer, no stand do ContilNet<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141729\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-35.jpeg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Eu e Mois\u00e9s fomos entrevistados pela influenciadora Ludmilla Cavalcante e pelo jornalista Douglas Richer, que derma um show na cobertura da Expoacre<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>S\u00e9rie de homenagens \u00e0 desembargadora Evan Evangelista, por sua aposentadoria, foi um dos assuntos mais comentados de setembro<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O m\u00eas de setembro ficou marcado pela s\u00e9rie de emocionantes homenagens prestadas pelo Tribunal de Justi\u00e7a do Acre e diversas institui\u00e7\u00f5es \u00e0 desembargadora <\/span><b>Eva Evangelista<\/b><span style=\"font-weight: 400;\">, que se aposentou ap\u00f3s uma trajet\u00f3ria exemplar e dedicada ao Judici\u00e1rio. A desembargadora, conhecida por sua sensibilidade e compromisso com a justi\u00e7a, se despediu do cargo rodeada de amigos e admiradores, que relembraram momentos marcantes de sua carreira. A celebra\u00e7\u00e3o foi uma verdadeira demonstra\u00e7\u00e3o de apre\u00e7o por sua contribui\u00e7\u00e3o ao Judici\u00e1rio e \u00e0 sociedade acreana.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No \u00faltimo dia 5 de setembro, os servidores e ex-servidores de seu gabinete tamb\u00e9m a homenagearam, com um jantar especial no AFA Bistr\u00f4. As homenagens foram repletas de carinho e gratid\u00e3o, refletindo o impacto positivo que Eva Evangelista deixou em cada um que teve o privil\u00e9gio de trabalhar ao seu lado.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141730\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-36.jpeg\" alt=\"\" width=\"834\" height=\"674\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A desembargadora Eva Evangelista com familiares e comigo, no jantar em sua homenagem<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141731\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-37.jpeg\" alt=\"\" width=\"1203\" height=\"998\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A l\u00edder com ex-servidores de seu gabinete, nos anos 2.000<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Simone Chaves celebra idade nova com tem\u00e1tica japonesa<\/b><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141732\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-38.jpeg\" alt=\"\" width=\"763\" height=\"982\" \/><\/p>\n<p><span style=\"font-weight: 400;\">No dia 7 de setembro, v\u00e9spera do seu anivers\u00e1rio, a m\u00e9dica <\/span><b>Simone Chaves<\/b><span style=\"font-weight: 400;\"> comemorou seu anivers\u00e1rio de forma especial em sua resid\u00eancia, cercada de amigos e familiares. O tema da festa foi uma homenagem ao Jap\u00e3o, inspirada na recente viagem que Simone fez ao pa\u00eds. A decora\u00e7\u00e3o exibia elementos t\u00edpicos da cultura japonesa, como lanternas de papel, origamis e flores de cerejeira, criando um ambiente encantador e acolhedor. Os convidados puderam degustar diversas del\u00edcias da culin\u00e1ria japonesa, incluindo sushi, sashimi e doces tradicionais, enquanto desfrutavam de momentos de alegria e descontra\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Caf\u00e9 com bolo<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Do jeitinho que costumo me reunir com amigos durante todo o ano, resolvi celebrar meu anivers\u00e1rio esse ano com um caf\u00e9, no final da tarde do dia 4 de setembro. Avisei familiares e amigos mais \u00edntimos que estaria no Caf\u00e9 do Teatro aguardando quem quisesse aparecer para me dar um abra\u00e7o e degustar um caf\u00e9 com bolo. Amei demais a presen\u00e7a e alegria dos queridos amigos que compareceram. Fiquei reenergizada!\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141733\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-39.jpeg\" alt=\"\" width=\"1280\" height=\"960\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Com o meu trio: Paulinho, Lu\u00edza e Felipe Pinheiro<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141734\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-40.jpeg\" alt=\"\" width=\"960\" height=\"988\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Meus amigos de todos os momentos C\u00e9sar J\u00fanior e Rayssa Alves, e o querid\u00edssimo Taison de Abreu, que estava em Rio Branco \u00e0 trabalho<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141734\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-40.jpeg\" alt=\"\" width=\"960\" height=\"988\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Claro que recebi o abra\u00e7o e dei boas risadas com os amigos colunistas sociais Giuliana Evangelista, Beth Passos, Mois\u00e9s Alencastro, M\u00e1rcia Abreu e Vagno Di Paula<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-141735\" src=\"https:\/\/nk7-testes.com.br\/wp-content\/uploads\/2024\/10\/Foto-41.jpeg\" alt=\"\" width=\"960\" height=\"915\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Gratid\u00e3o \u00e0s empres\u00e1rias In\u00eas e Claudinha Castro por organizarem a festa, em cima da hora. Rsrs. Ficou perfeita!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O Botic\u00e1rio transforma emo\u00e7\u00f5es em experi\u00eancias olfativas com a nova linha infantil de Divertida-Mente 2, em parceria com Disney e Pixar<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Identificar e expressar sentimentos durante a inf\u00e2ncia \u00e9 um processo fundamental no amadurecimento emocional das crian\u00e7as. Pensando em proporcionar experi\u00eancias positivas nesses momentos, <\/span><b>O Botic\u00e1rio<\/b><span style=\"font-weight: 400;\"> trouxe para as marcas infantis Sophie e Quasar Next uma linha completa inspirada em <\/span><b>Divertida-Mente 2, da Disney e Pixar,<\/b><span style=\"font-weight: 400;\"> filme que se tornou a maior bilheteria da hist\u00f3ria do cinema brasileiro. Os produtos possuem fragr\u00e2ncias que se conectam \u00e0s emo\u00e7\u00f5es do filme, desenvolvidas com ingredientes que despertam sensa\u00e7\u00f5es de bem-estar e alegria, comprovado pela neuroci\u00eancia.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com <\/span><b>dez produtos<\/b><span style=\"font-weight: 400;\">, a linha traz\u00a0 tr\u00eas op\u00e7\u00f5es de col\u00f4nias, aromatizador de ambientes, sabonete l\u00edquido, lo\u00e7\u00e3o hidratante, desodorante roll-on, leave-in com prote\u00e7\u00e3o t\u00e9rmica, n\u00e9cessaire e um livro, batizado de <\/span><b>Mapa das Emo\u00e7\u00f5es<\/b><span style=\"font-weight: 400;\">, foi idealizado pelo Botic\u00e1rio e co-criado com ag\u00eancia Almanaque e a editora Culturama, com atividades di\u00e1rias para que, junto aos tutores, as crian\u00e7as registrem e acompanhem os sentimentos delas em conte\u00fados exclusivos sobre o universo do filme Divertida-Mente 2, com apresenta\u00e7\u00e3o dos personagens para que aprendam sobre cada uma das emo\u00e7\u00f5es. O Botic\u00e1rio tamb\u00e9m fez parceria com a marca <\/span><b>Foroni<\/b><span style=\"font-weight: 400;\">, para o lan\u00e7amento de <\/span><b>cadernos universit\u00e1rios<\/b><span style=\"font-weight: 400;\"> inspirados na anima\u00e7\u00e3o, que trazem a perfuma\u00e7\u00e3o da fragr\u00e2ncia Col\u00f4nia Mem\u00f3rias no bolso interno; uma verdadeira explos\u00e3o de emo\u00e7\u00f5es para cria\u00e7\u00e3o de novas mem\u00f3rias.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Her Code Touch: fragr\u00e2ncia que inspira o prazer feminino pelo toque<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O conhecimento do pr\u00f3prio corpo \u00e9 o que potencializa o protagonismo da mulher na busca pelo autoprazer. Essa \u00e9 a principal mensagem de<\/span><b> Her Code Touch<\/b><span style=\"font-weight: 400;\">, lan\u00e7amento de Her Code, marca do Botic\u00e1rio criada em 2023 e a<\/span> <span style=\"font-weight: 400;\">primeira de perfumaria feminina da Am\u00e9rica Latina a se posicionar no territ\u00f3rio do prazer feminino<\/span><b>. <\/b><span style=\"font-weight: 400;\">Com a combina\u00e7\u00e3o do exclusivo <\/span><b>C\u00f3digo Secreto<\/b><span style=\"font-weight: 400;\">, acorde olfativo \u00fanico e instigante, \u00e0 sofistica\u00e7\u00e3o da <\/span><b>Baunilha Absoluta<\/b><span style=\"font-weight: 400;\">, a nova fragr\u00e2ncia incentiva a mulher a explorar e descobrir o seu prazer por meio do toque, revelando nuances quentes e sensuais que agu\u00e7am o prazer feminino.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">***<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O eau de parfum Her Code Touch, da fam\u00edlia olfativa Amadeirada Oriental, traz uma fragr\u00e2ncia sofisticada e envolvente. Suas notas de sa\u00edda combinam a vivacidade das frutas vermelhas com a leve refresc\u00e2ncia da bergamota. No cora\u00e7\u00e3o, o toque floral de jasmim e ylang ylang se une ao enigm\u00e1tico acorde c\u00f3digo secreto, criado pela renomada perfumista Louise Turner, da casa de fragr\u00e2ncia Givaudan, reconhecida por desenvolver diversas fragr\u00e2ncias femininas de sucesso do mercado internacional, potencializando a feminilidade intensa e sensual. Como oportunidade de compra, at\u00e9 o dia 13 de outubro, o eau de parfum <\/span><b>Her Code Touch <\/b><span style=\"font-weight: 400;\">conta com 13% de desconto em todas as lojas f\u00edsicas e no<\/span><a href=\"http:\/\/www.boticario.com.br\/\"> <span style=\"font-weight: 400;\">e-commerce<\/span><\/a><span style=\"font-weight: 400;\"> da marca, al\u00e9m do aplicativo Botic\u00e1rio, dispon\u00edvel para as vers\u00f5es Android e iOS.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong style=\"font-size: 12pt;\"><strong style=\"font-size: 12pt;\">\u00a0<\/strong><\/strong><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 13.2px;\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt; line-height: normal; text-align: center;\"><strong style=\"color: #000000; font-size: 16px; text-align: center;\"><span style=\"font-family: Verdana, sans-serif;\"><img decoding=\"async\" class=\" size-full wp-image-66615\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2020\/04\/gazeta_estilo_patrocinios.jpg\" alt=\"gazeta estilo patrocinios\" width=\"698\" height=\"160\" \/>\u00a0<\/span><\/strong><\/p>\n<p><strong style=\"font-size: 16px; text-align: center;\">\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donatinho, filho de Jo\u00e3o Donato, est\u00e1 no Acre gravando novo videoclipe No dia 7 de outubro, influenciadores, jornalistas e artistas participaram no Flutuante Malveira da grava\u00e7\u00e3o do videoclipe do single &#8220;Intuir&#8221;, feat do talentoso m\u00fasico Donatinho com seu pai Jo\u00e3o Donato. Com letras de Tulipa Ruiz e Gustavo Ruiz, essa m\u00fasica traz uma mensagem de [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":141740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"custom","single_blog_custom":"110746","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"1","show_inline_post_related":"0","post_calculate_word_method":"str_word_count"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0","format":"standard","jnews_video_option_group":[[]]},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_review":[],"enable_review":"0","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[{"good_text":""}],"bad":[{"bad_text":""}],"score_override":"0","override_value":"","rating":[{"rating_text":"","rating_number":"10"}],"price":[{"shop":"","price":"","link":"","icon":""}],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-141689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jackie-pinheiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLUNA JACKIE \u2013 09\/10\/2024 - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLUNA JACKIE \u2013 09\/10\/2024 - Agazeta.net\" \/>\n<meta property=\"og:description\" content=\"Donatinho, filho de Jo\u00e3o Donato, est\u00e1 no Acre gravando novo videoclipe No dia 7 de outubro, influenciadores, jornalistas e artistas participaram no Flutuante Malveira da grava\u00e7\u00e3o do videoclipe do single &#8220;Intuir&#8221;, feat do talentoso m\u00fasico Donatinho com seu pai Jo\u00e3o Donato. Com letras de Tulipa Ruiz e Gustavo Ruiz, essa m\u00fasica traz uma mensagem de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-09T21:58:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T12:28:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51-1024x530.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jackie Prinheiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jackie Prinheiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/\",\"name\":\"COLUNA JACKIE \u2013 09\/10\/2024 - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png\",\"datePublished\":\"2024-10-09T21:58:15+00:00\",\"dateModified\":\"2024-10-17T12:28:09+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png\",\"width\":1682,\"height\":870},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COLUNA JACKIE \u2013 09\/10\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\",\"name\":\"Jackie Prinheiro\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLUNA JACKIE \u2013 09\/10\/2024 - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"COLUNA JACKIE \u2013 09\/10\/2024 - Agazeta.net","og_description":"Donatinho, filho de Jo\u00e3o Donato, est\u00e1 no Acre gravando novo videoclipe No dia 7 de outubro, influenciadores, jornalistas e artistas participaram no Flutuante Malveira da grava\u00e7\u00e3o do videoclipe do single &#8220;Intuir&#8221;, feat do talentoso m\u00fasico Donatinho com seu pai Jo\u00e3o Donato. Com letras de Tulipa Ruiz e Gustavo Ruiz, essa m\u00fasica traz uma mensagem de [&hellip;]","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/","og_site_name":"Agazeta.net","article_published_time":"2024-10-09T21:58:15+00:00","article_modified_time":"2024-10-17T12:28:09+00:00","og_image":[{"width":1024,"height":530,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51-1024x530.png","type":"image\/png"}],"author":"Jackie Prinheiro","twitter_card":"summary_large_image","twitter_image":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png","twitter_misc":{"Escrito por":"Jackie Prinheiro","Est. tempo de leitura":"26 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/","name":"COLUNA JACKIE \u2013 09\/10\/2024 - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png","datePublished":"2024-10-09T21:58:15+00:00","dateModified":"2024-10-17T12:28:09+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/10\/Captura-de-Tela-2024-10-09-as-18.56.51.png","width":1682,"height":870},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-09-10-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"COLUNA JACKIE \u2013 09\/10\/2024"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c","name":"Jackie Prinheiro","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/141689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=141689"}],"version-history":[{"count":0,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/141689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/141740"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=141689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=141689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=141689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}