{"id":138558,"date":"2024-08-29T21:21:50","date_gmt":"2024-08-30T02:21:50","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=138558"},"modified":"2024-08-29T21:21:50","modified_gmt":"2024-08-30T02:21:50","slug":"coluna-jackie-27-08-2024","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/","title":{"rendered":"COLUNA JACKIE 27\/08\/2024"},"content":{"rendered":"<h2><img decoding=\"async\" class=\"alignnone size-full wp-image-138863\" style=\"color: #333333; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 15px;\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-6-jpeg.avif\" alt=\"\" width=\"1170\" height=\"1461\" \/><b><span data-contrast=\"auto\">Festival Ind\u00edgena Mariri Yawanawa: celebra\u00e7\u00e3o da cultura e espiritualidade<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">De 10 a 15 de agosto, a Aldeia Mutum se transformou em um vibrante palco para o <\/span><b><span data-contrast=\"auto\">Festival Ind\u00edgena Mariri Yawanawa<\/span><\/b><span data-contrast=\"auto\">, reunindo representantes das 17 aldeias do territ\u00f3rio ind\u00edgena do Rio Greg\u00f3rio. Este evento \u00e9 uma rica celebra\u00e7\u00e3o da cultura Yawanawa, repleta de canto, dan\u00e7a, cerim\u00f4nias, jogos e brincadeiras.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">***<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Na abertura, emocionantes momentos de espiritualidade, tradi\u00e7\u00e3o e uni\u00e3o, com uma bela cerim\u00f4nia \u00e0 sombra da Sama\u00fama secular, dan\u00e7as e cantos do povo Yawanawa. Os visitantes tiveram a oportunidade de vivenciar a express\u00e3o art\u00edstica e a cura tradicional, atrav\u00e9s das medicinas sagradas, al\u00e9m de mergulhar na profunda manifesta\u00e7\u00e3o cultural e espiritual do povo Yawanawa. Um momento de celebra\u00e7\u00e3o da e uma experi\u00eancia \u00fanica de se conectar com a sabedoria ancestral de um dos povos ind\u00edgenas mais fascinantes do Brasil. Fotos de Thiago Yawanawa, Jackie Pinheiro e Domingos Neto.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138859\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-2-1-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Abertura do festival com a travessia da ponte<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138860\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-3-jpeg.avif\" alt=\"\" width=\"1280\" height=\"960\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Algumas das autoridades presentes na cerim\u00f4nia de abertura realizada na sapopema da Sama\u00fama<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138861\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-4-jpeg.avif\" alt=\"\" width=\"1600\" height=\"1200\" \/>\u00a0<\/span><span data-contrast=\"auto\">Com o casal anfritri\u00e3o Tashka e Laura Yawanawa<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138862\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-5-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><img decoding=\"async\" class=\"alignnone size-full wp-image-138863\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-6-jpeg.avif\" alt=\"\" width=\"1170\" height=\"1461\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">O cacique geral Tashka Yawanawa e o cacique Shaneihu Yawanawa, da Aldeia Yawarani. \u00c0 direita, Tashka com o cacique Rasu e os paj\u00e9s Kuru e Matsini, todos da Aldeia Mutum, na cerim\u00f4nia de Uni<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138864\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-7-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138865\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-8-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Com Mois\u00e9s Alencastro, Bia Saldanha e o cineasta Est\u00eav\u00e3o Ciavatta, marido da artista Regina Cas\u00e9. \u00c0 direita, o cineasta Thiago Yawanawa, com a namorada Marciele Albuquerque, cunh\u00e3 poranga do Boi Caprichoso<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138866\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-9-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138867\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-10-jpeg.avif\" alt=\"\" width=\"890\" height=\"1280\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">A convite do casal Tashka Yawanawa, eu e Mois\u00e9s Alencastro participamos do festival com uma edi\u00e7\u00e3o especial do FestCine Origin\u00e1rios<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138868\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-11-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138869\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-12-1-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">\u00c0 esquerda, um registro do meu encontro com o cacique da Aldeia Nova Esperan\u00e7a, Iskukua Yawanawa. O casal Milena e Paka Yawanawa tamb\u00e9m esteve no festival. Ele \u00e9 a segunda lideran\u00e7a da Aldeia Yawarani<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138870\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-13-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138871\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-14-1-scaled.avif\" alt=\"\" width=\"1920\" height=\"2560\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Yawakashahu Yawanawa, cacique da Aldeia Mushuinu; e \u00e0 direita, o jovem cacique da Aldeia Mutum, Rasu Yawanawa<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138872\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-15-scaled.avif\" alt=\"\" width=\"1920\" height=\"2560\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138873\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-16-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Mois\u00e9s Alencastro com seu amigo Charles Yawanawa, cacique da Aldeia Shukuvena. \u00c0 direita, uma selfie com os queridos Panany Yawanawa e Rodrigo Siqueira, mineiro idealizador do perfil @indegenouscult, que estava cobrindo o festival<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138874\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-17-scaled.avif\" alt=\"\" width=\"1642\" height=\"2560\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138875\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-18-scaled.avif\" alt=\"\" width=\"1707\" height=\"2560\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">As artistas Dominique Nawama e Hukena Yawanawa, que resgatam cantos Yawanawa e encantam em suas viagens pelo pa\u00eds e exterior. \u00c0 direita, a cunh\u00e3 poranga do Boi Caprichoso, Marciele Albuquerque, uma das presen\u00e7as ilustres no festival<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138876\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-19-jpeg.avif\" alt=\"\" width=\"1262\" height=\"1600\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Eu e Mois\u00e9s com duas mulheres de for\u00e7a do povo Yawanawa: a coordenadora do festival, J\u00falia Yawanawa, e a diretora da Secretaria dos Povos Ind\u00edgenas, Nedina Yawanawa<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">\u00a0 <\/span> <span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138877\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-20-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138878\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-21-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Encontro com os diretores de cinema Gui Farias e Diogo Soares, que estavam filmando nas aldeias Yawarani e Mutum. Ao lado, com meu querido amigo e parceiro de d\u00e9cadas Tashka<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138879\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-22-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Salve, simpatia! As amigas Marciele Albuquerque e La\u00eds Brand\u00e3o distribuindo beleza e simpatia no festival<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138880\" style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-23-scaled.avif\" alt=\"\" width=\"2560\" height=\"1610\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Participa\u00e7\u00e3o feminina em uma das brincadeiras mais esperadas, o Kuxanai, onde os desafetos batem um no outro com talos de bananeira e fazem as pazes<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138881\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-24-scaled.avif\" alt=\"\" width=\"2560\" height=\"1742\" \/><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">As brincadeiras Yawanawa trazem muita alegria para os ind\u00edgenas e visitantes<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138882\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-25-jpeg.avif\" alt=\"\" width=\"1170\" height=\"1025\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Os jornalistas Altino Machado e N\u00e9lson Liano estavam presentes, acompanhando o amigo de profiss\u00e3o Rodrigo Mesquita, fundador do jornal Estad\u00e3o. Na foto, o trio \u00e0s margens do rio Greg\u00f3rio, no embarque para a aldeia<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Mois\u00e9s encontrou na Vila Vicente com a diretora de cinema Nicole Algrantti, que est\u00e1 concluindo um longa-metragem em homenagem a sua tia Clarice Lispector, dirigido por cinco mulheres. O filme \u201cRio de Clarice\u201d \u00e9 fruto de projeto aprovado na lei de incentivo \u00e0 cultura Paulo Gustavo. Viva o audiovisual!\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Projeto FestCine Origin\u00e1rios realiza edi\u00e7\u00e3o especial no Mariri Yawanawa<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Com grande alegria, o idealizador do projeto <\/span><b><span data-contrast=\"auto\">FestCine Origin\u00e1rios,<\/span><\/b><span data-contrast=\"auto\"> produtor cultural <\/span><b><span data-contrast=\"auto\">Mois\u00e9s Alencastro<\/span><\/b><span data-contrast=\"auto\">, realizou uma edi\u00e7\u00e3o especial no Festival Ind\u00edgena <\/span><b><span data-contrast=\"auto\">Mariri Yawanawa<\/span><\/b><span data-contrast=\"auto\">, a convite do cacique geral <\/span><b><span data-contrast=\"auto\">Tashka Yawanawa<\/span><\/b><span data-contrast=\"auto\">. Esta foi a primeira vez que o FestCine Origin\u00e1rios se juntou a esse importante evento, trazendo uma sele\u00e7\u00e3o de filmes produzidos e dirigidos por ind\u00edgenas do Acre. Durante o festival, os participantes e ind\u00edgenas puderam assistir a uma programa\u00e7\u00e3o especial com seis curtas-metragens e um document\u00e1rio que refletem a cultura, a luta e a sabedoria ancestral dos povos origin\u00e1rios. O projeto FestCine Origin\u00e1rios contou com o apoio cultural da <\/span><b><span data-contrast=\"auto\">Secretaria de Estado de Comunica\u00e7\u00e3o<\/span><\/b><span data-contrast=\"auto\"> e da <\/span><b><span data-contrast=\"auto\">Secretaria Municipal de Turismo<\/span><\/b><span data-contrast=\"auto\">, al\u00e9m da parceria da <\/span><b><span data-contrast=\"auto\">Associa\u00e7\u00e3o Sociocultural Yawanawa<\/span><\/b><span data-contrast=\"auto\"> e do<\/span><b><span data-contrast=\"auto\"> Cine Clube Mira\u00e7\u00e3o<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138884\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-27-scaled.avif\" alt=\"\" width=\"1874\" height=\"2560\" \/><\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138885\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-28.-1-jpeg.avif\" alt=\"\" width=\"959\" height=\"1140\" \/><\/p>\n<p><span data-contrast=\"auto\">O coordenador do FestCine Origin\u00e1rios Mois\u00e9s Alencastro e a produtora dessa edi\u00e7\u00e3o, Jackie Pinheiro, na viagem de barco pelo rio Greg\u00f3rio; e na chegada na aldeia Mutum, com o cacique geral Tashka Yawanawa<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">A Expoacre 2024 j\u00e1 tem sua nova Rainha do Rodeio\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">A bela <\/span><b><span data-contrast=\"auto\">Hilary Katryne<\/span><\/b><span data-contrast=\"auto\"> \u00e9 a nova Rainha do Rodeio da Expoacre 2024, ap\u00f3s disputado concurso ocorrido no s\u00e1bado, 24, na Esplanada do Pal\u00e1cio Rio Branco. Doze concorrentes disputaram o t\u00edtulo, no certame organizado pela Associa\u00e7\u00e3o dos Colunistas do Acre (Acos) e governo do Acre, por meio da Secretaria de Estado de Turismo e Empreendedorismo (Sete), com apoio de empresas e fazendas parceiras. Veja alguns dos melhores momentos da festa. Fotos de Alice Le\u00e3o\/Sete.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138886\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-29-1-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">A nova Rainha, Hilary Katryne, com a Rainha do Rodeio da Expoacre 202, Lohana Martins<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138887\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-30-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Hilary Katryne \u00e9 a Rainha do Rodeio da Expoacre 2024<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138888\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-31-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Sarah Cristinny \u00e9 a Princesa do La\u00e7o da Expoacre 2024<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138889\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-32-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Eduarda Freitas, de Senador Guiomard, \u00e9 a Madrinha dos Pe\u00f5es da Expoacre 2024<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138890\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-34-scaled.avif\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">O concurso foi marcado pelas apresenta\u00e7\u00f5es, com tocar do berrante, estalo da muxinga e outros talentos das candidatas<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">O Botic\u00e1rio celebra a beleza do ver\u00e3o do Norte<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Celebrar a beleza, a diversidade e a cultura de cada regi\u00e3o do Brasil, tornou-se um pilar do Botic\u00e1rio e, pensando nisso, foi lan\u00e7ada a campanha <\/span><b><span data-contrast=\"auto\">Viva a Beleza do seu Ver\u00e3o<\/span><\/b><span data-contrast=\"auto\">, que este ano contempla os estados do Par\u00e1, Amap\u00e1, Amazonas, Tocantins, Acre e Rond\u00f4nia, em per\u00edodos diferentes, tendo como objetivo valorizar as caracter\u00edsticas \u00fanicas do ver\u00e3o na regi\u00e3o Norte do Brasil.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">***<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">No Acre, uma a\u00e7\u00e3o foi realizada no munic\u00edpio de Feij\u00f3, no Festival de Praia e Festival do A\u00e7a\u00ed de Feij\u00f3, um dos principais destinos escolhidos pelos acreanos, para curtir o auge do ver\u00e3o amaz\u00f4nico. De 16 a 18 de agosto, o carrinho m\u00f3vel do Botic\u00e1rio esteve na praia e na pra\u00e7a da bandeira, na \u00e1rea central da cidade, oferecendo experimenta\u00e7\u00e3o de fragr\u00e2ncias e produtos de cuidados, e um espa\u00e7o instagram\u00e1vel para fotos, al\u00e9m de distribui\u00e7\u00e3o de brindes e \u00f3culos solares. As influenciadoras<\/span><b><span data-contrast=\"auto\"> Matilde Silva, Camilla Costa, Katyana Aguiar<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Mailly Lawrence <\/span><\/b><span data-contrast=\"auto\">participaram da ativa\u00e7\u00e3o e mostraram tudo em suas redes sociais.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138891\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-35-1-jpeg.avif\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">A\u00e7\u00e3o da campanha <\/span><b><span data-contrast=\"auto\">Viva a Beleza do seu Ver\u00e3o, <\/span><\/b><span data-contrast=\"auto\">do Botic\u00e1rio, no festival de praia de Feij\u00f3<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138892\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-36-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138893\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-37-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">As lindas influenciadoras Camilla Costa e Mailly Lawrence<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138894\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-38-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138895\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-39-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">As estrelas Katyana Aguiar e Matilde Silva cobriram a a\u00e7\u00e3o e fizeram dezenas de fotos com seus seguidores<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Inaugura\u00e7\u00e3o do Centro de Atendimento ao Turista\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138896\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-40-jpeg.avif\" alt=\"\" width=\"1600\" height=\"1200\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Na inaugura\u00e7\u00e3o do Centro de Atendimento ao Turista, ocorrida no dia 5, com o secret\u00e1rio municipal de Turismo, <\/span><b><span data-contrast=\"auto\">Ezequiel Bino<\/span><\/b><span data-contrast=\"auto\">, sua esposa <\/span><b><span data-contrast=\"auto\">Kelly Gouveia<\/span><\/b><span data-contrast=\"auto\">, e o colunista <\/span><b><span data-contrast=\"auto\">Mois\u00e9s Alencastro<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Exposi\u00e7\u00e3o na Europa<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138897\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-41-jpeg.avif\" alt=\"\" width=\"1170\" height=\"860\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">O artista pl\u00e1stico acreano<\/span><b><span data-contrast=\"auto\"> Fernando Fran\u00e7a<\/span><\/b><span data-contrast=\"auto\"> retornou recentemente de uma temporada na Europa, onde participou de uma exposi\u00e7\u00e3o em Hajd\u00fab\u00f6sz\u00f6rm\u00e9ny, na Hungria, que contou com a presen\u00e7a do prefeito Attila Kiss. De l\u00e1, ele seguiu para a It\u00e1lia, onde visitou as cidades de Padova, Verona e Veneza, para conferir a Bienal de Veneza.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/agencia.ac.gov.br\/wp-content\/uploads\/2024\/08\/IMG_0107-scaled.jpg\"><span data-contrast=\"auto\">\ufddfHYPERLINK &#8220;https:\/\/agencia.ac.gov.br\/wp-content\/uploads\/2024\/08\/IMG_0107-scaled.jpg&#8221;<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: left;\"><b><span data-contrast=\"auto\">Palestra no WILD 12<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138898\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-42-jpeg.avif\" alt=\"\" width=\"1170\" height=\"1428\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">O casal <\/span><b><span data-contrast=\"auto\">Tashka<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Laura<\/span><\/b> <b><span data-contrast=\"auto\">Yawanawa<\/span><\/b><span data-contrast=\"auto\"> proferiu palestra ontem, 26, no <\/span><b><span data-contrast=\"auto\">12th World Wilderness Congress\u202f<\/span><\/b><span data-contrast=\"auto\">&#8211; WILD 12, ocorrido em Black Hills, em Dakota do Sul, nos Estados Unidos.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Os 21 anos dos Los Porongas<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138899\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-43-jpeg.avif\" alt=\"\" width=\"1200\" height=\"1600\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Vale ainda um registro dos bastidores do show em celebra\u00e7\u00e3o aos 21 anos de estrada da banda de rock autoral <\/span><b><span data-contrast=\"auto\">Los Porongas<\/span><\/b><span data-contrast=\"auto\">, ocorrido no dia 13 de julho \u2013 dia do rock -, durante o Acre Rock Festival, na Concha Ac\u00fastica. Nas fotos, os m\u00fasicos<\/span><b><span data-contrast=\"auto\"> M\u00e1rcio Murad, Jorge Anzol<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Jo\u00e3o Vasconcelos<\/span><\/b><span data-contrast=\"auto\"> comigo e os m\u00fasicos mineiros <\/span><b><span data-contrast=\"auto\">Laura C\u00e2ndida<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Pablo C\u00e2ndida.<\/span><\/b><span data-contrast=\"auto\"> \u00c0 direita, o vocalista <\/span><b><span data-contrast=\"auto\">Diogo<\/span><\/b> <b><span data-contrast=\"auto\">Soares<\/span><\/b><span data-contrast=\"auto\"> com sua filha <\/span><b><span data-contrast=\"auto\">Alice<\/span><\/b><span data-contrast=\"auto\">, eu e o l\u00edder ind\u00edgena <\/span><b><span data-contrast=\"auto\">Paka Yawanawa<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Inaugura\u00e7\u00e3o do Picanha Mix Parque<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Com imensa alegria, o casal <\/span><b><span data-contrast=\"auto\">Tamires Almeida<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Moacir J\u00fanior<\/span><\/b><span data-contrast=\"auto\"> recebeu autoridades, imprensa, influenciadores digitais e convidados para a noite inaugural do Picanha Mix Parque, no dia 4 de julho. A casa j\u00e1 \u00e9 sucesso, com seu excelente atendimento e card\u00e1pio ecl\u00e9tico.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138900\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-45-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Na noite inaugural, com a querida empres\u00e1ria Tamires Almeida<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138901\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-46-1-jpeg.avif\" alt=\"\" width=\"1600\" height=\"1066\" \/><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">O casal anfitri\u00e3o, Tamires Almeida e Moacir J\u00fanior<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138902\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-47-1-jpeg.avif\" alt=\"\" width=\"1600\" height=\"1066\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Flaviano Melo, presidente do MDB, esteve presente<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138903\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-48-1-jpeg.avif\" alt=\"\" width=\"1600\" height=\"1066\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">O senador M\u00e1rcio Bittar entre amigos<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Anivers\u00e1rio da chef Socorro Jorge<\/span><\/b><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138904\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-49-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-138905\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-50-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"1280\" \/><\/p>\n<p><span data-contrast=\"auto\">Em tempo, registro alguns momentos do anivers\u00e1rio da madrinha dos colunistas sociais, <\/span><b><span data-contrast=\"auto\">Socorro Jorge<\/span><\/b><span data-contrast=\"auto\">, renomada chef de cozinha acreana, celebrado no dia 10 de julho, no seu restaurante Point do Pato, com a presen\u00e7a de amigos e familiares. Na foto, a aniversariante, seu filho <\/span><b><span data-contrast=\"auto\">Henrique Jorge<\/span><\/b><span data-contrast=\"auto\"> e eu.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Laura C\u00e2ndida realiza dois shows em Rio Branco<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img decoding=\"async\" class=\"alignnone size-full wp-image-138906\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-51-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"816\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0Julho foi um m\u00eas cultural. Entre os bons shows ocorridos na cidade, destacamos os shows da artista mineira <\/span><b><span data-contrast=\"auto\">Laura C\u00e2ndida<\/span><\/b><span data-contrast=\"auto\">, nos dias 13 e 14, no Cine Teatro Recreio, pelo projeto <\/span><b><span data-contrast=\"auto\">Festival Sol Maior<\/span><\/b><span data-contrast=\"auto\">, que contou com as participa\u00e7\u00f5es especiais de <\/span><b><span data-contrast=\"auto\">Elis<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Rog\u00e9rio<\/span><\/b> <b><span data-contrast=\"auto\">Craveiro<\/span><\/b><span data-contrast=\"auto\">, <\/span><b><span data-contrast=\"auto\">Dito<\/span><\/b> <b><span data-contrast=\"auto\">Bruzugu<\/span><\/b><span data-contrast=\"auto\">, <\/span><b><span data-contrast=\"auto\">Diogo Soares<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Jo\u00e3o Vasconcelos<\/span><\/b><span data-contrast=\"auto\">. Ela e seu produtor musical e companheiro de palco <\/span><b><span data-contrast=\"auto\">Pablo C\u00e2ndido<\/span><\/b><span data-contrast=\"auto\"> realizaram ainda a Oficina de Inspira\u00e7\u00e3o, Composi\u00e7\u00e3o e Criatividade, no dia 13, no mesmo local. Na foto, a equipe de produ\u00e7\u00e3o do show, <\/span><b><span data-contrast=\"auto\">Eufr\u00e1sio Moraes, Let\u00edcia Moura, Jackie Pinheiro<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Eddie Trindade.<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Temporada de shows com Jo\u00e3o Vasconcelos<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138907\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-52-1-jpeg.avif\" alt=\"\" width=\"960\" height=\"931\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">A passagem do m\u00fasico <\/span><b><span data-contrast=\"auto\">Jo\u00e3o Vasconcelos<\/span><\/b><span data-contrast=\"auto\"> por Rio Branco foi totalmente musical. Al\u00e9m do show de 21\u00ba anivers\u00e1rio dos Los Porongas, ele tamb\u00e9m realizou o <\/span><b><span data-contrast=\"auto\">Especial<\/span><\/b> <b><span data-contrast=\"auto\">Beatles<\/span><\/b><span data-contrast=\"auto\">, no dia 12, e o <\/span><b><span data-contrast=\"auto\">Especial<\/span><\/b> <b><span data-contrast=\"auto\">Belchior<\/span><\/b><span data-contrast=\"auto\">, no dia 18, ambos na Casa do Poeta. E rolou ainda mais uma edi\u00e7\u00e3o do <\/span><b><span data-contrast=\"auto\">Especial<\/span><\/b> <b><span data-contrast=\"auto\">Beatles<\/span><\/b><span data-contrast=\"auto\">, no dia 19, na Confraria, com as participa\u00e7\u00f5es dos m\u00fasicos <\/span><b><span data-contrast=\"auto\">Pedro Arco<\/span><\/b><span data-contrast=\"auto\"> e <\/span><b><span data-contrast=\"auto\">Jorge Anzol<\/span><\/b><span data-contrast=\"auto\">. Na foto, eu com ele e o querido poeta<\/span><b><span data-contrast=\"auto\"> C\u00e9sar Augusto<\/span><\/b><span data-contrast=\"auto\">, o <\/span><b><span data-contrast=\"auto\">Cesinha<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Visita ilustre<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"><img decoding=\"async\" class=\"alignnone size-full wp-image-138908\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-53-1-jpeg.avif\" alt=\"\" width=\"900\" height=\"1084\" \/>\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Minha querida amiga <\/span><b><span data-contrast=\"auto\">Marilene Costa<\/span><\/b><span data-contrast=\"auto\">, que hoje reside em Jo\u00e3o Pessoa, com a filha <\/span><b><span data-contrast=\"auto\">Thain\u00e1 Matias, <\/span><\/b><span data-contrast=\"auto\">passou o m\u00eas de julho em Rio Branco revendo familiares, a pedido do filho <\/span><b><span data-contrast=\"auto\">Thales Matias<\/span><\/b><span data-contrast=\"auto\">. Na foto, n\u00f3s duas na rede colorida do restaurante Mata Nativa, onde almo\u00e7amos com familiares dela, ap\u00f3s um treininho na Smart Fit.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b><span data-contrast=\"auto\">Cuide-se Bem e Egeo com fragr\u00e2ncia inspirada em melancia<\/span><\/b><i><span data-contrast=\"auto\">\u00a0<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138909\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-54-1-jpg.avif\" alt=\"\" width=\"1920\" height=\"1384\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Sucesso entre a Gera\u00e7\u00e3o Z, as fragr\u00e2ncias frutais t\u00eam ganhado cada vez mais relev\u00e2ncia e conquistado espa\u00e7o entre as escolhas dos consumidores. De olho nesse comportamento, o <\/span><b><span data-contrast=\"auto\">Botic\u00e1rio <\/span><\/b><span data-contrast=\"auto\">atendeu aos in\u00fameros pedidos da comunidade de <\/span><i><span data-contrast=\"auto\">brand lovers<\/span><\/i><span data-contrast=\"auto\"> e lan\u00e7ou, em maio de 2024, duas fragr\u00e2ncias de edi\u00e7\u00e3o limitada inspiradas na fruta <\/span><i><span data-contrast=\"auto\">hit <\/span><\/i><span data-contrast=\"auto\">do momento, que registrou um desfecho hist\u00f3rico para a marca: o estoque originalmente previsto para durar 14 dias, esgotou em apenas 57 horas, comprovando a assertividade do lan\u00e7amento. Como continuidade desse sucesso, a marca acaba de integrar a fragr\u00e2ncia <\/span><b><span data-contrast=\"auto\">Egeo Melancia<\/span><\/b><span data-contrast=\"auto\"> ao seu portf\u00f3lio e ganhar novos integrantes \u00e0 fam\u00edlia Melancia, agora com <\/span><b><span data-contrast=\"auto\">Cuide-se Bem Melancia<\/span><\/b><span data-contrast=\"auto\">, uma linha de edi\u00e7\u00e3o limitada que faz jus ao tamanho da fruta, com oito produtos inspirados no seu cheirinho delicioso. Uma del\u00edcia!\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559737&quot;:-182,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Promo na linha Make B.<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-138910\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-55-jpg.avif\" alt=\"\" width=\"517\" height=\"357\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">At\u00e9 o dia 1\u00ba de setembro, <\/span><b><span data-contrast=\"auto\">Make B.<\/span><\/b><span data-contrast=\"auto\">, marca de maquiagem do Botic\u00e1rio que une alta performance e tecnologia, ir\u00e1 oferecer at\u00e9 35% de desconto em todo o seu portf\u00f3lio. Com a promo\u00e7\u00e3o, a marca, que n\u00e3o costuma promover grandes descontos, proporciona aos consumidores a oportunidade \u00fanica de garantir seus produtos queridinhos, como a <\/span><b><span data-contrast=\"auto\">Base L\u00edquida Glycolic TX<\/span><\/b><span data-contrast=\"auto\"> e a <\/span><b><span data-contrast=\"auto\">M\u00e1scara de C\u00edlios 4K Panoramic<\/span><\/b><span data-contrast=\"auto\">, por pre\u00e7os especiais.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">***<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para dar continuidade \u00e0 produ\u00e7\u00e3o e evidenciar a beleza de forma sofisticada e elegante, as <\/span><b><span data-contrast=\"auto\">Palettes de Sombras e Rosto Make B. One<\/span><\/b><span data-contrast=\"auto\"> s\u00e3o ideais. A de rosto \u00e9 multifuncional e oferece 12 op\u00e7\u00f5es de tons entre iluminadores, blushes e contornos com acabamentos mate, acetinado e brilho. A de sombras possui 24 tons dentre marrom, rosados e neutros. Esses e outros itens da linha Make B. est\u00e3o com pre\u00e7os promocionais.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559731&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong style=\"font-size: 12pt;\"><strong style=\"font-size: 12pt;\">\u00a0<\/strong><\/strong><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 13.2px;\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt; line-height: normal; text-align: center;\"><strong style=\"color: #000000; font-size: 16px; text-align: center;\"><span style=\"font-family: Verdana, sans-serif;\"><img decoding=\"async\" class=\" size-full wp-image-66615\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2020\/04\/gazeta_estilo_patrocinios.jpg\" alt=\"gazeta estilo patrocinios\" width=\"698\" height=\"160\" \/>\u00a0<\/span><\/strong><\/p>\n<p><strong style=\"font-size: 16px; text-align: center;\">\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festival Ind\u00edgena Mariri Yawanawa: celebra\u00e7\u00e3o da cultura e espiritualidade\u00a0 \u00a0 De 10 a 15 de agosto, a Aldeia Mutum se transformou em um vibrante palco para o Festival Ind\u00edgena Mariri Yawanawa, reunindo representantes das 17 aldeias do territ\u00f3rio ind\u00edgena do Rio Greg\u00f3rio. Este evento \u00e9 uma rica celebra\u00e7\u00e3o da cultura Yawanawa, repleta de canto, dan\u00e7a, [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":138858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"custom","single_blog_custom":"110746","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"1","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_review":[],"enable_review":"0","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[{"good_text":""}],"bad":[{"bad_text":""}],"score_override":"0","override_value":"","rating":[{"rating_text":"","rating_number":"10"}],"price":[{"shop":"","price":"","link":"","icon":""}],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-138558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jackie-pinheiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLUNA JACKIE 27\/08\/2024 - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLUNA JACKIE 27\/08\/2024 - Agazeta.net\" \/>\n<meta property=\"og:description\" content=\"Festival Ind\u00edgena Mariri Yawanawa: celebra\u00e7\u00e3o da cultura e espiritualidade\u00a0 \u00a0 De 10 a 15 de agosto, a Aldeia Mutum se transformou em um vibrante palco para o Festival Ind\u00edgena Mariri Yawanawa, reunindo representantes das 17 aldeias do territ\u00f3rio ind\u00edgena do Rio Greg\u00f3rio. Este evento \u00e9 uma rica celebra\u00e7\u00e3o da cultura Yawanawa, repleta de canto, dan\u00e7a, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T02:21:50+00:00\" \/>\n<meta name=\"author\" content=\"Jackie Prinheiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jackie Prinheiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/\",\"name\":\"COLUNA JACKIE 27\/08\/2024 - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-1-1-scaled-1.avif\",\"datePublished\":\"2024-08-30T02:21:50+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-1-1-scaled-1.avif\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-1-1-scaled-1.avif\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COLUNA JACKIE 27\/08\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\",\"name\":\"Jackie Prinheiro\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLUNA JACKIE 27\/08\/2024 - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"COLUNA JACKIE 27\/08\/2024 - Agazeta.net","og_description":"Festival Ind\u00edgena Mariri Yawanawa: celebra\u00e7\u00e3o da cultura e espiritualidade\u00a0 \u00a0 De 10 a 15 de agosto, a Aldeia Mutum se transformou em um vibrante palco para o Festival Ind\u00edgena Mariri Yawanawa, reunindo representantes das 17 aldeias do territ\u00f3rio ind\u00edgena do Rio Greg\u00f3rio. Este evento \u00e9 uma rica celebra\u00e7\u00e3o da cultura Yawanawa, repleta de canto, dan\u00e7a, [&hellip;]","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/","og_site_name":"Agazeta.net","article_published_time":"2024-08-30T02:21:50+00:00","author":"Jackie Prinheiro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jackie Prinheiro","Est. tempo de leitura":"28 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/","name":"COLUNA JACKIE 27\/08\/2024 - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-1-1-scaled-1.avif","datePublished":"2024-08-30T02:21:50+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-1-1-scaled-1.avif","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/08\/Foto-1-1-scaled-1.avif","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-27-08-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"COLUNA JACKIE 27\/08\/2024"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c","name":"Jackie Prinheiro","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/138558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=138558"}],"version-history":[{"count":0,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/138558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/138858"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=138558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=138558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=138558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}