{"id":135209,"date":"2024-07-05T10:44:20","date_gmt":"2024-07-05T15:44:20","guid":{"rendered":"https:\/\/nk7-testes.com.br\/agazeta\/?p=135209"},"modified":"2024-07-05T10:44:20","modified_gmt":"2024-07-05T15:44:20","slug":"coluna-jackie-05-07-2024","status":"publish","type":"post","link":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/","title":{"rendered":"COLUNA JACKIE 05\/07\/2024"},"content":{"rendered":"<h2><strong>Thiago Yawanaw\u00e1 celebra a vit\u00f3ria do Boi Caprichoso com sua cunh\u00e3 poranga Marciele Albuquerque<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135211\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp\" alt=\"\" width=\"1834\" height=\"1170\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp 1834w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg-300x191.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg-1024x653.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg-768x490.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg-1536x980.webp 1536w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg-750x478.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg-1140x727.webp 1140w\" sizes=\"(max-width: 1834px) 100vw, 1834px\" \/><\/p>\n<p>Enquanto a na\u00e7\u00e3o azul celebrava a vit\u00f3ria do Boi Garantido, no Festival Folcl\u00f3rico de Parintins, o ind\u00edgena acreano <strong>Thiago Yawanaw\u00e1<\/strong> acompanhou toda a agenda de festejos ao lado de sua amada, a Cunh\u00e3 Poranga do boi azul, <strong>Marciele<\/strong> <strong>Albuquerque<\/strong>, na Ilha da Magia, onde acontece uma das maiores festas culturais do pa\u00eds, reconhecido como patrim\u00f4nio cultural do pa\u00eds pelo Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional (Iphan). Anteontem, ele embarcou para Manaus-AM, para alguns dias de descanso.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Filha de Chico Mendes desfila pelo Boi Garantido<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135212\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-2-jpg.webp\" alt=\"\" width=\"582\" height=\"734\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-2-jpg.webp 582w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-2-jpg-238x300.webp 238w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><\/p>\n<p>Quem tamb\u00e9m desfilou no \u00faltimo dia do Festival Folcl\u00f3rido 2024 em Parintins, esse ano, foi a filha primog\u00eanita de Chico Mendes, e atual presidente do Instituto Chico Mendes, <strong>\u00c2ngela Mendes<\/strong>. Ela entrou no Bumb\u00f3dromo ao lado do criador de conte\u00fado ind\u00edgena <strong>Jos\u00e9 Kaet\u00ea<\/strong>, conhecido nas redes sociais como @zenarede, com uma mensagem em conex\u00e3o com o espet\u00e1culo \u201cAmaz\u00f4nia Nossa Luta em Poesia\u201d, pelo Boi Garantido, no dia 29 de junho. Estreou com o p\u00e9 direito pelo boi campe\u00e3o do festival.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>Ministra Marina Silva cumpre agenda no Acre<\/strong><\/h2>\n<p>A ministra do Meio Ambiente <strong>Marina<\/strong> <strong>Silva<\/strong> esteve em Rio Branco recentemente e participou de algumas agendas, sobre sustentabilidade e o combate \u00e0 mudan\u00e7a do clima. Pela manh\u00e3, ela ministrou uma palestra com o tema \u201cA crise clim\u00e1tica e os impactos na vida dos acreanos\u201d, no Museu dos Povos Acreanos. Depois, cumpriu agenda pol\u00edtica com os pr\u00e9-candidatos a vereadores da Rede Sustentabilidade, partido fundado pela acreana, onde debateu sobre o papel das elei\u00e7\u00f5es municipais e do controle social no enfrentamento da crise clim\u00e1tica, no audit\u00f3rio da Fecom\u00e9rcio. Esse tema precisa estar presentes nos planos de governo dos candidatos que v\u00e3o disputar as elei\u00e7\u00f5es, segundo a Ministra.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Ela fez ainda uma visita ao poeta <strong>C\u00e9sar<\/strong> <strong>F\u00e9lix<\/strong> e sua m\u00e3e <strong>Raimundinha<\/strong>, no Caf\u00e9 com Poesia, onde conversou com amigos, saboreou um quibe de arroz e declamou poesias.<\/p>\n<p style=\"text-align: center;\"><strong> <img decoding=\"async\" class=\"alignnone size-full wp-image-135213\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-3-jpeg.webp\" alt=\"\" width=\"457\" height=\"425\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-3-jpeg.webp 457w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-3-jpeg-300x279.webp 300w\" sizes=\"(max-width: 457px) 100vw, 457px\" \/><\/strong><\/p>\n<p style=\"text-align: center;\">A ministra acreana Marina Silva com o porta-voz masculino da Rede Sustentabilidade, In\u00e1cio Moreira. Ao seu lado, o senador S\u00e9rgio Petec\u00e3o, na agenda pol\u00edtica<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135214\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg.webp\" alt=\"\" width=\"1952\" height=\"1120\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg.webp 1952w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg-300x172.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg-1024x588.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg-768x441.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg-1536x881.webp 1536w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg-750x430.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-4-jpeg-1140x654.webp 1140w\" sizes=\"(max-width: 1952px) 100vw, 1952px\" \/><\/p>\n<p style=\"text-align: center;\">Com o poeta C\u00e9sar F\u00e9lix e sua m\u00e3e Raimundinha. \u00c0 direita, com a porta-voz feminina da Rede Sustentabilidade, Jana\u00edna Queiroz<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Cinema poss\u00edvel<\/strong><\/h2>\n<p>O cineasta acreano <strong>Teddy Falc\u00e3o<\/strong> ministrar\u00e1 o curso &#8220;O FilmEscola Por um Cinema Poss\u00edvel&#8221; no Coworking Casa Urbana, de 8 a 10 de junho. Ser\u00e3o tr\u00eas dias intensivos para quem quer mergulhar no mundo do audiovisual, aprendendo tudo sobre roteiro, produ\u00e7\u00e3o, fotografia, dire\u00e7\u00e3o, montagem e edi\u00e7\u00e3o.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Para se inscrever, basta acessar o link <a href=\"https:\/\/www.even3.com.br\/ofilmescola\/\">https:\/\/www.even3.com.br\/ofilmescola\/<\/a> at\u00e9 o dia 6. As inscri\u00e7\u00f5es s\u00e3o gratuitas e a lista de aprovados sai no domingo, 7, no Instagram @saturnoapc.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Al\u00e9m do pr\u00f3prio Teddy, o curso contar\u00e1 com a participa\u00e7\u00e3o de profissionais como a fot\u00f3grafa <strong>Deyse Cruz<\/strong>, a cineasta <strong>Juliana Machado<\/strong>, o diretor <strong>Ney Ricardo<\/strong>, a fot\u00f3grafa <strong>Hannah Lydia<\/strong> e o realizador <strong>Eduardo Fragoso<\/strong>. Uma super oportunidade pra quem quer se qualificar na \u00e1rea! O curso \u00e9 uma produ\u00e7\u00e3o da Saturno Produ\u00e7\u00e3o e Audiovisual, com financiamento do Governo Federal pela Lei Paulo Gustavo e apoio da Funda\u00e7\u00e3o Garibaldi Brasil.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Terceira edi\u00e7\u00e3o do Acre Rock Festival acontecer\u00e1 no dia mundial do rock<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135215\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5.jpeg\" alt=\"\" width=\"1280\" height=\"1280\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5.jpeg 1280w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-300x300.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-1024x1024.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-150x150.webp 150w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-768x768.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-75x75.webp 75w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-350x350.webp 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-750x750.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-1140x1140.webp 1140w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-5-400x400.webp 400w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>A terceira edi\u00e7\u00e3o do <strong>Acre<\/strong> <strong>Rock<\/strong> <strong>Festival<\/strong> acontecer\u00e1 no dia 13 de julho, na Concha Ac\u00fastica, no Dia Mundial do Rock, com a participa\u00e7\u00e3o de dez bandas. O evento totalmente gratuito \u00e9 uma promo\u00e7\u00e3o da Associa\u00e7\u00e3o de M\u00fasicos e Produtores Culturais Independentes do Acre (Amupac) e ter\u00e1 a participa\u00e7\u00e3o da banda carioca <strong>Baia<\/strong> e o reencontro do quarteto dos <strong>Los<\/strong> <strong>Porongas<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Reencontro da banda Los Porongas celebra os 21 anos de carreira<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135216\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg.webp\" alt=\"\" width=\"1280\" height=\"848\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg.webp 1280w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg-300x199.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg-1024x678.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg-768x509.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg-750x497.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-6-jpeg-1140x755.webp 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>A banda <strong>Los Porongas<\/strong> comemora 21 anos de carreira em 2024. Ap\u00f3s o lan\u00e7amento de tr\u00eas discos &#8211; Los Porongas (2007), O Segundo Depois do Sil\u00eancio (2011) e Infinito Agora (2015) &#8211; al\u00e9m de dois DVDs e do reconhecimento nacional, a banda se re\u00fane no Acre, durante o <strong>Acre Rock Festival<\/strong>, para celebrar sua trajet\u00f3ria com a forma\u00e7\u00e3o original: <strong>Diogo Soares<\/strong> (voz), <strong>Jo\u00e3o Vasconcelos <\/strong>(guitarra), <strong>M\u00e1rcio Magr\u00e3o<\/strong> (baixo) e <strong>Jorge Anzol<\/strong> (bateria), contando tamb\u00e9m com a participa\u00e7\u00e3o de <strong>Saulo Ol\u00edmpio<\/strong> (guitarra). Juntos, eles reviver\u00e3o as can\u00e7\u00f5es que marcaram uma gera\u00e7\u00e3o e colocaram o Acre no mapa da m\u00fasica pop brasileira. O festival acontecer\u00e1 no dia 13 de julho, dia mundial do rock, na Concha Ac\u00fastica.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135217\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg.webp\" alt=\"\" width=\"1170\" height=\"1056\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg.webp 1170w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg-300x271.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg-1024x924.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg-768x693.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg-750x677.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-7-jpeg-1140x1029.webp 1140w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><\/p>\n<p style=\"text-align: center;\">O vocalista Diogo Soares celebrar\u00e1 tamb\u00e9m no show seus 43 anos de idade, assinalados no dia 2 de julho<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Mariri Yawanaw\u00e1<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135218\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-8-jpeg.webp\" alt=\"\" width=\"1032\" height=\"1280\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-8-jpeg.webp 1032w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-8-jpeg-242x300.webp 242w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-8-jpeg-826x1024.webp 826w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-8-jpeg-768x953.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-8-jpeg-750x930.webp 750w\" sizes=\"(max-width: 1032px) 100vw, 1032px\" \/><\/p>\n<p>Falta apenas um m\u00eas para a realiza\u00e7\u00e3o do grande festival <strong>Mariri Yawanawa 2024<\/strong>, o festival pioneiro que abriu portas para que as etnias possam fazer esse interc\u00e2mbio cultural, de fomento ao turismo, com pessoas dos munic\u00edpios acreanos, demais estados do pa\u00eds e at\u00e9 do exterior. Idealizado pelo l\u00edder <strong>Tashka Yawanawa<\/strong>, o festival acontecer\u00e1 na Aldeia Mutum, de 10 a 15 de agosto, localizada no Rio Greg\u00f3rio, com cantos, dan\u00e7a, reza, cura, arte, manifesta\u00e7\u00f5es culturais e espirituais.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Degusta\u00e7\u00e3o no Quiosque Lugano<\/strong><\/h2>\n<p>No dia 28 de junho, a empres\u00e1ria <strong>Aline Schenneider<\/strong> recebeu colunistas sociais e influenciadores digitais no rec\u00e9m inaugurado <strong>Quiosque Lugano<\/strong>, para uma degusta\u00e7\u00e3o harmonizada de vinhos e chocolates, o carro-chefe da casa. Localizado no Via Verde Shopping, o Quiosque Lugano oferece a exclusividade dos Chocolates de Gramado Lugano, al\u00e9m de vinhos finos e outras bebidas n\u00e3o alc\u00f3olicas.<\/p>\n<p>Os anfitri\u00f5es, a empres\u00e1ria Aline Schenneider e os representantes do marketing do shopping \u2013 Daniel Ferreira e Neia Aielo -, com os colunistas Mois\u00e9s Alencastro, M\u00e1rcia Abreu, Beth Passos, Jackie Pinheiro, Robertha Moura, Roberta Lima e Gigi Hanan<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135219\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-9-jpeg.webp\" alt=\"\" width=\"960\" height=\"839\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-9-jpeg.webp 960w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-9-jpeg-300x262.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-9-jpeg-768x671.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-9-jpeg-750x655.webp 750w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p style=\"text-align: center;\">Com a empres\u00e1ria Aline Schenneider e a publicit\u00e1ria Neia Aielo<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135220\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-10-jpeg.webp\" alt=\"\" width=\"960\" height=\"880\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-10-jpeg.webp 960w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-10-jpeg-300x275.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-10-jpeg-768x704.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-10-jpeg-750x688.webp 750w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p style=\"text-align: center;\">Encontro com os queridos influenciadores Ramayano Souza, Estella Martins, Andrey Maia e Juliana Melo<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135221\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-11-jpeg.webp\" alt=\"\" width=\"960\" height=\"858\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-11-jpeg.webp 960w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-11-jpeg-300x268.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-11-jpeg-768x686.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-11-jpeg-750x670.webp 750w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p style=\"text-align: center;\">Neia e Aline comigo e as queridas Kelly Kley, Meyre Manaus e Beth Passos<\/p>\n<p style=\"text-align: center;\">\n<h2><strong>Arrai\u00e1 dos B\u00e3o Via Verde Shopping<\/strong><\/h2>\n<p>Essa \u00e9 pra quem gosta de arraial! E n\u00e3o tem \u00e9poca mais animada do que os meses de junho e julho, n\u00e3o \u00e9 mesmo? O Via Verde Shopping estar\u00e1 realizando na sua pra\u00e7a de alimenta\u00e7\u00e3o, de 18h \u00e0s 21h, o <strong>Arrai\u00e1 dos B\u00e3o<\/strong>, com comidas t\u00edpicas, forr\u00f3, bingo, brincadeiras e muito entretenimento.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Treinamento em comunica\u00e7\u00e3o digital<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135223\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg.webp\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg.webp 1080w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-300x300.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-1024x1024.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-150x150.webp 150w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-768x768.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-75x75.webp 75w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-350x350.webp 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-750x750.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-13-jpeg-400x400.webp 400w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>Uma das maiores marcas do marketing pol\u00edtico e comunica\u00e7\u00e3o p\u00fablica, pol\u00edtica e institucional do Brasil, o Reboot, chega ao Acre no dia 6 de julho, de 8 \u00e0s 18h, para um treinamento imersivo de um dia inteiro sobre planejamento e estrat\u00e9gia em comunica\u00e7\u00e3o pol\u00edtica, p\u00fablica e institucional, e tr\u00e1fego pago. O evento, que ser\u00e1 realizado na Est\u00e1cio Unimeta, est\u00e1 com inscri\u00e7\u00f5es abertas pelo Sympla. (<a href=\"https:\/\/www.sympla.com.br\/treinamento-imersivo-planejamento-e-estrategia-em-comunicacao-politica-publica-e-institucional__2501136\">https:\/\/www.sympla.com.br\/treinamento-imersivo-planejamento-e-estrategia-em-comunicacao-politica-publica-e-institucional__2501136<\/a>), e pelo telefone (68) 99283-3838.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Voltado para profissionais de comunica\u00e7\u00e3o, assessores de imprensa e assessores pol\u00edticos, que atuam em processo eleitoral e comunica\u00e7\u00e3o p\u00fablica e institucional, o treinamento contar\u00e1 com as presen\u00e7as de Nani Blanco, publicit\u00e1ria e diretora da Ag\u00eancia Nuvem em Bras\u00edlia, coordenadora do Semin\u00e1rio Reboot, e Danilo Nogueira, especialista em comunica\u00e7\u00e3o on-line, com enfoque em tr\u00e1fego pago. O treinamento imersivo \u00e9 uma realiza\u00e7\u00e3o da Reboot Escola, da Ag\u00eancia Nuvem (Bras\u00edlia), e a Ponte \u2013 Comunica\u00e7\u00e3o e Marketing (Acre), com apoio da ACISA, Federacre, Wave Produ\u00e7\u00f5es e \u00c9 Pop.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Laura C\u00e2ndida faz shows e oficina em Rio Branco<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135224\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg.webp\" alt=\"\" width=\"1641\" height=\"1024\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg.webp 1641w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg-300x187.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg-1024x639.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg-768x479.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg-1536x958.webp 1536w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg-750x468.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-14-jpg-1140x711.webp 1140w\" sizes=\"(max-width: 1641px) 100vw, 1641px\" \/><\/p>\n<p>A maravilhosa artista mineira <strong>Laura C\u00e2ndido <\/strong>estar\u00e1 em Rio Branco no pr\u00f3ximo final de semana comandando dois shows nos dias 13 e 14 de julho, \u00e0s 19h, no Cine Teatro Recreio. E no dia 13, de 9 \u00e0s 12h, ela ministrar\u00e1 uma Oficina de Inspira\u00e7\u00e3o, Composi\u00e7\u00e3o e Criatividade. Oportunidades incr\u00edveis!<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Estetic Face<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135225\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg.webp\" alt=\"\" width=\"1786\" height=\"1036\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg.webp 1786w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg-300x174.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg-1024x594.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg-768x445.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg-1536x891.webp 1536w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg-750x435.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-15-jpg-1140x661.webp 1140w\" sizes=\"(max-width: 1786px) 100vw, 1786px\" \/><\/p>\n<p>Eu e o colega <strong>Mois\u00e9s Alencastro<\/strong> estivemos essa semana estivemos na <strong>Estetic Face<\/strong>, com a dra. <strong>Sandra Aguiar<\/strong>, para nos inteirarmos das novidades. Na cl\u00ednica s\u00e3o realizados procedimentos est\u00e9ticos como aplica\u00e7\u00e3o de botox, blefaroplastia, endolaser, lipo de papada, lobuloplastia, alectomia e muitos outros. O sucesso da m\u00e9dica \u00e9 not\u00f3rio, tanto \u00e9 que agora ela viaja com frequ\u00eancia para Curitiba, onde tamb\u00e9m inaugurou uma cl\u00ednica. Informa\u00e7\u00f5es pelos telefones (68) 2102-6493 e 99612-5984.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Cadeira Emsella chega na Cliago<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135226\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg.webp\" alt=\"\" width=\"1834\" height=\"1340\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg.webp 1834w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg-300x219.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg-1024x748.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg-768x561.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg-1536x1122.webp 1536w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg-750x548.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-16-jpeg-1140x833.webp 1140w\" sizes=\"(max-width: 1834px) 100vw, 1834px\" \/><\/p>\n<p>Chegou h\u00e1 duas semanas na <strong>Cliago<\/strong>, cl\u00ednica m\u00e9dica comandada pela m\u00e9dica <strong>Thaysa Vilela<\/strong>, a cadeira <strong>Emsella<\/strong>, uma tecnologia revolucion\u00e1ria com o potencial de promover 11.000 contra\u00e7\u00f5es perineais em 28 minutos, indicada para o tratamento de incontin\u00eancia urin\u00e1ria, frouxid\u00e3o no assoalho p\u00e9lvico e fortalecimento per\u00edneo p\u00f3s-parto. Para mais informa\u00e7\u00f5es entre em contato pelo telefone (68) 99913-6312 ou no Instagram @drathaysavilela.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Conex\u00e3o empresarial com elas<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135227\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-17-jpeg.webp\" alt=\"\" width=\"1065\" height=\"1280\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-17-jpeg.webp 1065w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-17-jpeg-250x300.webp 250w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-17-jpeg-852x1024.webp 852w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-17-jpeg-768x923.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-17-jpeg-750x901.webp 750w\" sizes=\"(max-width: 1065px) 100vw, 1065px\" \/><\/p>\n<p>A mentora e palestrante <strong>Simone Casas<\/strong> realizar\u00e1 a primeira edi\u00e7\u00e3o do &#8220;Left Hand: Conex\u00e3o Empresarial com Elas&#8221;, no pr\u00f3ximo dia 8 de julho, no Hotel Villa Rio Branco, com o objetivo de promover o fortalecimento do empreendedorismo feminino. O evento re\u00fane 30 mulheres empreendedoras e a imprensa, em uma noite com a realiza\u00e7\u00e3o de palestra, pitchs de apresenta\u00e7\u00e3o, v\u00eddeo, fotos, sorteios, jantar e caf\u00e9, risadas e boas conex\u00f5es.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>Boas novas<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135228\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18.jpeg 1280w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18-300x225.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18-1024x768.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18-768x576.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18-750x563.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-18-1140x855.webp 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Reuni\u00e3o e cafezinho com a competente jornalista e querida amiga <a href=\"https:\/\/www.facebook.com\/maria.meirelles.31?__cft__%5b0%5d=AZXDo3LS6MC6IB19Hfqx0a1yJhEtt2wTawjX2AHOGVOEQfrFijEMUGsifBXkomb8RmgrMQunNnIknGUtel5q8qFtj7Yb57eXXlEG_W4bPDhT8bKxYU2YCgFYKCR8gX0edh2UwM9rNmt1MKjLT2ZL3WqobfksB2mNaNYz_la5GU0IlfmtChEVbquW_k9U57NuWgUbpQCMY9ZMveTOc-pJrOoP&amp;__tn__=-%5dK-R\"><strong>Maria Meirelles<\/strong><\/a>, no dia 2, no Casar\u00e3o Caf\u00e9, sobre um projeto cultural na \u00e1rea de audiovisual idealizado pelo produtor cultural e colunista social <a href=\"https:\/\/www.facebook.com\/moises.alencastro.9?__cft__%5b0%5d=AZXDo3LS6MC6IB19Hfqx0a1yJhEtt2wTawjX2AHOGVOEQfrFijEMUGsifBXkomb8RmgrMQunNnIknGUtel5q8qFtj7Yb57eXXlEG_W4bPDhT8bKxYU2YCgFYKCR8gX0edh2UwM9rNmt1MKjLT2ZL3WqobfksB2mNaNYz_la5GU0IlfmtChEVbquW_k9U57NuWgUbpQCMY9ZMveTOc-pJrOoP&amp;__tn__=-%5dK-R\"><strong>Mois\u00e9s Alencastro<\/strong><\/a>. Eu tamb\u00e9m estarei no time da comunica\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>O Botic\u00e1rio e Paramount se unem para o lan\u00e7amento de Cuide-se Bem Bob Esponja<\/strong><\/h2>\n<p>Voc\u00eas est\u00e3o prontos, botilovers? No ano de celebra\u00e7\u00e3o dos 25 anos de Bob Esponja, Cuide-se Bem \u2013 marca de cuidados pessoais do Botic\u00e1rio, conhecida pelos seus lan\u00e7amentos ic\u00f4nicos e collabs desejadas \u2013 uniu-se a Paramount, por meio de seu departamento de Licenciamento de Produtos e Experi\u00eancias, para apresentar <strong>Cuide-se Bem Bob Esponja<\/strong>, linha de edi\u00e7\u00e3o limitada inspirada nos personagens da franquia, que traz cheirinho inspirado em abacaxi em itens para o cuidado corporal e facial, banho, make, al\u00e9m de acess\u00f3rios, convidando os consumidores a trazerem mais otimismo para a rotina de autocuidado.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Assim como o personagem, conhecido por seu otimismo implac\u00e1vel e alegria contagiante, Cuide-se Bem carrega a leveza e divers\u00e3o como pilares na idealiza\u00e7\u00e3o de novas linhas e produtos, al\u00e9m de um olhar cuidadoso e atento com sustentabilidade. Toda a linha apresenta itens 100% veganos e com alta porcentagem de ingredientes naturais, enquanto os itens enxagu\u00e1veis s\u00e3o os primeiros a apresentarem o selo \u201cf\u00f3rmula amiga das \u00e1guas\u201d e o sabonete l\u00edquido que apresenta o primeiro frasco PE PCR (embalagens feitas a partir de pl\u00e1stico reciclado p\u00f3s-consumo) do Grupo Botic\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Linha Cuide-se Bem Bob Esponja possui 14 itens<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135229\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg.webp\" alt=\"\" width=\"1280\" height=\"914\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg.webp 1280w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-300x214.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-1024x731.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-768x548.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-120x86.webp 120w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-350x250.webp 350w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-750x536.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-19-jpeg-1140x814.webp 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Com fam\u00edlia olfativa Frutal Gourmand, que apresenta notas, como abacaxi tropical, flor de laranjeira, pina colada e espumante ros\u00e9, a fragr\u00e2ncia de todos os itens foi inspirada no cheirinho de abacaxi \u2013 um elemento \u00edcone da anima\u00e7\u00e3o. Em uma variedade de texturas e benef\u00edcios, a linha explora ao m\u00e1ximo a experi\u00eancia sensorial da Fenda do Biqu\u00edni e conta com um amplo portf\u00f3lio de 14 itens. Entre eles, produtos para o corpo, como o <strong>Hidratante Corporal do Bob Esponja<\/strong> e <strong>Hidratante Corporal Sandy Bochechas<\/strong>, fornecem 48 horas de hidrata\u00e7\u00e3o e textura cremosa. J\u00e1 a<strong> Geleia Hidratante Corporal Lula Molusco<\/strong> traz uma textura de gelatina ultraleve, com sensa\u00e7\u00e3o refrescante e r\u00e1pida absor\u00e7\u00e3o, e tamb\u00e9m o <strong>Creme Hidratante Para M\u00e3os Gary<\/strong>, que promete uma textura em gel-creme, nutrindo e protegendo as m\u00e3os da perda de \u00e1gua \u2013 al\u00e9m de alto n\u00edvel de fofura com embalagem que faz alus\u00e3o ao formato real do personagem.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>A linha de banho traz o <strong>Sabonete L\u00edquido Patrick Estrela<\/strong> e o <strong>Sabonete em Barra Bob Esponja <\/strong>com formato do personagem, que garantem pele macia e perfumada, al\u00e9m de uma espuma cremosa. H\u00e1 tamb\u00e9m o queridinho <strong>Body Splash <\/strong>para manter a pele perfumada, o<strong> Desodorante Antitranspirante Roll On<\/strong> <strong>48h,<\/strong> que \u00e9 geladinho e refrescante como a brisa do mar, com secagem r\u00e1pida que mant\u00e9m a hidrata\u00e7\u00e3o natural da pele, e o<strong> Gel de Limpeza Facial,<\/strong> que purifica e remove o excesso de oleosidade mantendo a hidrata\u00e7\u00e3o natural da pele. Para os amantes de make, o portf\u00f3lio tamb\u00e9m conta com uma <strong>Paleta Multifuncional<\/strong> de quatro cores, com dois diferentes tipos de acabamento (mate e superbrilho), que podem ser usados como blush e iluminador, al\u00e9m do <strong>Lip Tint Patrick Estrela e Lip Tint Sandy Bochechas<\/strong>, com duas op\u00e7\u00f5es de cores (rosa e coral), que proporcionam apar\u00eancia de l\u00e1bios e bochechas saud\u00e1veis, f\u00e1cil de espalhar e construir camadas.\u00a0 Para complementar a linha, o <strong>n\u00e9cessaire <\/strong>\u00e9 a op\u00e7\u00e3o perfeita para carregar os itens, e o <strong>kit presente\u00e1vel<\/strong> incentiva os consumidores a presentear amigos queridos, refor\u00e7ando uma das caracter\u00edsticas mais marcantes da anima\u00e7\u00e3o: a amizade dos personagens.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>Voc\u00eas est\u00e3o prontos para uma viagem \u00e0 Fenda do Biqu\u00edni?<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135230\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg.webp\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg.webp 1280w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg-300x200.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg-1024x682.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg-768x512.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg-750x500.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-20-jpeg-1140x760.webp 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong>Cuide-se Bem Bob Esponja <\/strong>deseja revelar algo curioso e especial: os ingredientes secretos da f\u00f3rmula da amizade, celebrando as diferen\u00e7as, a divers\u00e3o e o mais importante: o cuidado. Pensando nisso, a marca apostou em uma estrat\u00e9gia focada em gerar conversa e conectar a comunidade com um tema t\u00e3o genu\u00edno, que engaja e converte, convocando os consumidores a conhecerem a f\u00f3rmula da amizade.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Para impulsionar o lan\u00e7amento, a marca lan\u00e7ar\u00e1 um challenge nas redes sociais desafiando duplas de amigos a concorrerem \u00e0 viagem e criarem mem\u00f3rias inesquec\u00edveis, como, com certeza, j\u00e1 tiveram assistindo ao desenho. Para participar, os consumidores devem soltar a criatividade em um v\u00eddeo contando a hist\u00f3ria e conex\u00e3o dessa rela\u00e7\u00e3o de amizade e basta apenas usar o \u00e1udio (dispon\u00edvel no perfil oficial da marca no TikTok) e hashtags oficiais da campanha (#CuideSeBemBobEsponja). A a\u00e7\u00e3o promocional ter\u00e1 dois vencedores com direito a acompanhante, que ganhar\u00e3o uma viagem para o Nickelodeon Hotels &amp; Resorts Riviera Maya, al\u00e9m de um kit completo com todos os itens da nova linha. Veja os detalhes sobre a a\u00e7\u00e3o promocional <a href=\"https:\/\/www.promocuidesebembobesponja.com.br\/\">neste<\/a><a href=\"https:\/\/www.promocuidesebembobesponja.com.br\/\"> link<\/a>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135231\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg.webp\" alt=\"\" width=\"1702\" height=\"1273\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg.webp 1702w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg-300x224.webp 300w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg-1024x766.webp 1024w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg-768x574.webp 768w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg-1536x1149.webp 1536w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg-750x561.webp 750w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-21-jpeg-1140x853.webp 1140w\" sizes=\"(max-width: 1702px) 100vw, 1702px\" \/><\/p>\n<p>O conceito da campanha e estrat\u00e9gia de conte\u00fado se alinham a uma data que est\u00e1 presente no m\u00eas do lan\u00e7amento: o <strong>Dia do Amigo<\/strong>, celebrado em 20 de julho, \u00e9 um gancho interessante para refor\u00e7ar a linha como um item presente\u00e1vel na data<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Botic\u00e1rio apresenta novo Coffee Addictive<\/strong><\/h2>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135236\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Imagem1.png\" alt=\"\" width=\"594\" height=\"396\" srcset=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Imagem1.png 594w, https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Imagem1-300x200.png 300w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/><\/p>\n<p>Sedu\u00e7\u00e3o e irrever\u00eancia s\u00e3o caracter\u00edsticas essenciais para manter qualquer relacionamento em dia. Pensando nisso, <strong>Coffee<\/strong>, uma das principais marcas de perfumaria do <strong>Botic\u00e1rio<\/strong>, traz o lan\u00e7amento de uma dupla de fragr\u00e2ncias inspiradas nos sofisticados drinks, o agito das festas e a pot\u00eancia do desejo, combinando frutalidade e frescor com a sensualidade sofisticada e viciante do caf\u00e9 e de notas adocicadas. Desde o dia 1\u00ba de julho, <strong>Coffee Addictive<\/strong> chegou em todos os canais do Botic\u00e1rio e promete agitar a rotina, como uma op\u00e7\u00e3o e convite para surpreender quem se ama.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>O segredinho do lan\u00e7amento de perfumaria s\u00e3o as notas vindas da infus\u00e3o do caf\u00e9 ar\u00e1bica que, combinadas com o dul\u00e7or da baunilha e do \u00e2mbar, respectivamente, revelam duas fragr\u00e2ncias deliciosamente envolventes. <strong>Coffee Addictive Oriental Frutal<\/strong> carrega uma perfuma\u00e7\u00e3o sedutora, com topo de frutas vermelhas combinada com a feminilidade das flores de jasmim e rosas e um toque adocicado da baunilha. J\u00e1 o <strong>Coffee Addictive Oriental Arom\u00e1tico<\/strong> une notas de topo com o frescor arom\u00e1tico do cardamomo e noz-moscada, com corpo composto por lavanda e alecrim, e fundo de cedro, \u00e2mbar e as notas de caf\u00e9.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Como oportunidade de compra, entre os dias 1\u00ba e 27 de julho, as fragr\u00e2ncias <strong>Coffee Addictive<\/strong> contam com desconto especial de 20% em todos os canais de compras do Botic\u00e1rio.<\/p>\n<p style=\"text-align: center;\"><strong style=\"font-size: 12pt;\"><strong style=\"font-size: 12pt;\">\u00a0<\/strong><\/strong><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 13.2px;\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: 0.0001pt; line-height: normal; text-align: center;\"><strong style=\"color: #000000; font-size: 16px; text-align: center;\"><span style=\"font-family: Verdana, sans-serif;\"><img decoding=\"async\" class=\" size-full wp-image-66615\" src=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2020\/04\/gazeta_estilo_patrocinios.jpg\" alt=\"gazeta estilo patrocinios\" width=\"698\" height=\"160\" \/>\u00a0<\/span><\/strong><\/p>\n<p><strong style=\"font-size: 16px; text-align: center;\">\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thiago Yawanaw\u00e1 celebra a vit\u00f3ria do Boi Caprichoso com sua cunh\u00e3 poranga Marciele Albuquerque Enquanto a na\u00e7\u00e3o azul celebrava a vit\u00f3ria do Boi Garantido, no Festival Folcl\u00f3rico de Parintins, o ind\u00edgena acreano Thiago Yawanaw\u00e1 acompanhou toda a agenda de festejos ao lado de sua amada, a Cunh\u00e3 Poranga do boi azul, Marciele Albuquerque, na Ilha [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":135211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"custom","single_blog_custom":"110746","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"1","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_review":[],"enable_review":"0","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[{"good_text":""}],"bad":[{"bad_text":""}],"score_override":"0","override_value":"","rating":[{"rating_text":"","rating_number":"10"}],"price":[{"shop":"","price":"","link":"","icon":""}],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-135209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jackie-pinheiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLUNA JACKIE 05\/07\/2024 - Agazeta.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLUNA JACKIE 05\/07\/2024 - Agazeta.net\" \/>\n<meta property=\"og:description\" content=\"Thiago Yawanaw\u00e1 celebra a vit\u00f3ria do Boi Caprichoso com sua cunh\u00e3 poranga Marciele Albuquerque Enquanto a na\u00e7\u00e3o azul celebrava a vit\u00f3ria do Boi Garantido, no Festival Folcl\u00f3rico de Parintins, o ind\u00edgena acreano Thiago Yawanaw\u00e1 acompanhou toda a agenda de festejos ao lado de sua amada, a Cunh\u00e3 Poranga do boi azul, Marciele Albuquerque, na Ilha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Agazeta.net\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T15:44:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1834\" \/>\n\t<meta property=\"og:image:height\" content=\"1170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jackie Prinheiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jackie Prinheiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/\",\"name\":\"COLUNA JACKIE 05\/07\/2024 - Agazeta.net\",\"isPartOf\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp\",\"datePublished\":\"2024-07-05T15:44:20+00:00\",\"author\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\"},\"breadcrumb\":{\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#primaryimage\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp\",\"contentUrl\":\"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp\",\"width\":1834,\"height\":1170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/nk7-testes.com.br\/agazeta\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COLUNA JACKIE 05\/07\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#website\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/\",\"name\":\"Agazeta.net\",\"description\":\"Agazeta.net - Not\u00edcias de Rio Branco\/AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c\",\"name\":\"Jackie Prinheiro\",\"url\":\"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLUNA JACKIE 05\/07\/2024 - Agazeta.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"COLUNA JACKIE 05\/07\/2024 - Agazeta.net","og_description":"Thiago Yawanaw\u00e1 celebra a vit\u00f3ria do Boi Caprichoso com sua cunh\u00e3 poranga Marciele Albuquerque Enquanto a na\u00e7\u00e3o azul celebrava a vit\u00f3ria do Boi Garantido, no Festival Folcl\u00f3rico de Parintins, o ind\u00edgena acreano Thiago Yawanaw\u00e1 acompanhou toda a agenda de festejos ao lado de sua amada, a Cunh\u00e3 Poranga do boi azul, Marciele Albuquerque, na Ilha [&hellip;]","og_url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/","og_site_name":"Agazeta.net","article_published_time":"2024-07-05T15:44:20+00:00","og_image":[{"width":1834,"height":1170,"url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp","type":"image\/webp"}],"author":"Jackie Prinheiro","twitter_card":"summary_large_image","twitter_image":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp","twitter_misc":{"Escrito por":"Jackie Prinheiro","Est. tempo de leitura":"28 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/","url":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/","name":"COLUNA JACKIE 05\/07\/2024 - Agazeta.net","isPartOf":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#primaryimage"},"image":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp","datePublished":"2024-07-05T15:44:20+00:00","author":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c"},"breadcrumb":{"@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#primaryimage","url":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp","contentUrl":"https:\/\/nk7-testes.com.br\/agazeta\/wp-content\/uploads\/2024\/07\/Foto-1-jpg.webp","width":1834,"height":1170},{"@type":"BreadcrumbList","@id":"https:\/\/nk7-testes.com.br\/agazeta\/coluna-jackie-05-07-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nk7-testes.com.br\/agazeta\/"},{"@type":"ListItem","position":2,"name":"COLUNA JACKIE 05\/07\/2024"}]},{"@type":"WebSite","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#website","url":"https:\/\/nk7-testes.com.br\/agazeta\/","name":"Agazeta.net","description":"Agazeta.net - Not\u00edcias de Rio Branco\/AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nk7-testes.com.br\/agazeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/nk7-testes.com.br\/agazeta\/#\/schema\/person\/5c620c97f99c38b7460daae5a337477c","name":"Jackie Prinheiro","url":"https:\/\/nk7-testes.com.br\/agazeta\/author\/jackie-pinheiro\/"}]}},"_links":{"self":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/135209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/comments?post=135209"}],"version-history":[{"count":0,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/posts\/135209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media\/135211"}],"wp:attachment":[{"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/media?parent=135209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/categories?post=135209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nk7-testes.com.br\/agazeta\/wp-json\/wp\/v2\/tags?post=135209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}